{"id":13807,"date":"2022-01-19T16:33:35","date_gmt":"2022-01-19T21:33:35","guid":{"rendered":"https:\/\/mathemalchemy.org\/2022\/01\/19\/cabalgata-conexiones-matematicas\/"},"modified":"2025-12-15T14:54:01","modified_gmt":"2025-12-15T19:54:01","slug":"cabalgata-conexiones-matematicas","status":"publish","type":"post","link":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/","title":{"rendered":"Cabalgata &#8211; Conexiones matem\u00e1ticas"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull coblocks-animate\" data-coblocks-animation=\"fadeIn\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" class=\"wp-block-cover__image-background wp-image-5030\" alt=\"\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=900%2C900&#038;ssl=1\" data-object-fit=\"cover\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1568%2C1568&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-primary-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cavalcade\">Cabalgata<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"mathematical-connections\">Conexiones matem\u00e1ticas<\/h3>\n<\/div><\/div>\n\n<h4 class=\"wp-block-heading\" id=\"about-the-cavalcade\">Sobre la Cabalgata<\/h4>\n\n<p>La colecci\u00f3n de hojas es muy diversa, y abarca desde figuras interesantes y\/o bellas a divertidas an\u00e9cdotas, pasando por visualizaciones \u00abaj\u00e1\u00bb y documentos o reflexiones hist\u00f3ricas; algunas de ellas rinden homenaje a un matem\u00e1tico concreto. No hay ninguna raz\u00f3n matem\u00e1tica que justifique su orden aqu\u00ed: se trata simplemente del orden en que se fabricaron, que se reg\u00eda en parte por su ajuste a los metros de tela en los que se imprimieron.   <\/p>\n\n<p>El orden en que aparecen en la instalaci\u00f3n puede variar de una construcci\u00f3n a otra: el orden f\u00edsico se adapta a los \u00e1ngulos visuales de cada lugar cuando se monta la instalaci\u00f3n para su exposici\u00f3n.<\/p>\n\n<p>A continuaci\u00f3n se enumeran las fichas, con una breve explicaci\u00f3n de cada una.<\/p>\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Archimedes: Volume of the sphere<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\" id=\"Archimedes-Volume-of-the-sphere\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"Arqu&#xED;medes: Volumen de la esfera\" class=\"wp-image-4660\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=900%2C1200&amp;ssl=1 900w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?resize=1200%2C1600&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/archimedes_volume_of_sphere-1-mathemalchemy-art-installation.jpg?w=1256&amp;ssl=1 1256w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Los diagramas de esta p\u00e1gina esbozan una modernizaci\u00f3n del c\u00e1lculo de Arqu\u00edmedes del volumen de una esfera. Este logro es especialmente impresionante, ya que Arqu\u00edmedes obtuvo el volumen dos milenios antes de la aparici\u00f3n del c\u00e1lculo, en una \u00e9poca y un lugar en los que el cero y los n\u00fameros negativos no eran conceptos aceptados. <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>El argumento esencial es que el volumen de la esfera m\u00e1s el volumen del cono deben ser iguales al volumen del cilindro, porque la relaci\u00f3n correspondiente es v\u00e1lida para el \u00e1rea de sus secciones transversales bidimensionales a cada altura. Dado que el volumen del cilindro es \u03c0r<sup>2<\/sup>h= 2\u03c0r<sup>3,<\/sup> y el volumen del doble cono (f\u00f3rmula m\u00e1s sencilla de deducir) es 2(1\/3)\u03c0r<sup>2<\/sup>h= (2\/3)\u03c0r<sup>3<\/sup>, obtenemos la f\u00f3rmula moderna del volumen de una esfera, (4\/3)\u03c0r<sup>3<\/sup>. <\/p>\n<\/div><\/details><\/div>\n<\/div>\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Factorization Diagrams<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\" id=\"eratosthenes-geometrically\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=900%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-10833\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?resize=1568%2C1568&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?w=2001&amp;ssl=1 2001w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/Factorization-Diagrams-image.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<p>Cada n\u00famero N entre 1 y 100 se representa mediante una figura con N puntos, dispuestos sim\u00e9tricamente. Si N es compuesto, N=KxL, entonces la disposici\u00f3n refleja las construcciones de los n\u00fameros m\u00e1s peque\u00f1os K y L: se pueden reconocer como bloques de construcci\u00f3n de N. Los n\u00fameros primos destacan como c\u00edrculos simples; son los mismos n\u00fameros que quedar\u00e1n al descubierto en la Criba <a href=\"http:\/\/en.wikipedia.org\/wiki\/Sieve_of_Eratosthenes\" target=\"_blank\" rel=\"noreferrer noopener\">de Erat\u00f3stenes<\/a>, despu\u00e9s de que la criba del 7 se encaje en su lugar en el <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/jardin-conexiones-matematicas\/\">Jard\u00edn de MatemAlquimia<\/a>, \u00a1como la ardilla Tassos est\u00e1 ocupada explicando! <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Complex Cubic Numbers<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/complex-cubic-numbers-mathemalchemy-art-installation.jpg?resize=791%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4663\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/complex-cubic-numbers-mathemalchemy-art-installation.jpg?resize=791%2C1024&amp;ssl=1 791w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/complex-cubic-numbers-mathemalchemy-art-installation.jpg?resize=232%2C300&amp;ssl=1 232w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/complex-cubic-numbers-mathemalchemy-art-installation.jpg?resize=768%2C994&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/complex-cubic-numbers-mathemalchemy-art-installation.jpg?w=850&amp;ssl=1 850w\" sizes=\"auto, (max-width: 791px) 100vw, 791px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta imagen es un ejemplo de un Paisaje Estelar Algebraico, descrito por Edmund Harriss, Kate Stange y Steve Trettel en el art\u00edculo <em><a href=\"https:\/\/algebraicstarscapes.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Paisajes estelares num\u00e9ricos algebraicos<\/a>.<\/em> Estos intrincados patrones muestran la belleza de resolver ecuaciones polinomiales. Los puntos de esta imagen representan las ra\u00edces complejas de los polinomios c\u00fabicos ax<sup>3<\/sup>+bx<sup>2<\/sup>+cx+b= 0, cuyo tama\u00f1o se hace m\u00e1s peque\u00f1o a medida que el polinomio se hace m\u00e1s complejo (intuitivamente, esto se relaciona con que a,b y c se hacen m\u00e1s grandes, pero en realidad es la ra\u00edz c\u00fabica del discriminante). El punto hacia el que parece atraer toda la imagen es i, la ra\u00edz cuadrada de -1. <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Los puntos de esta imagen representan las ra\u00edces complejas de los polinomios c\u00fabicos ax<sup>3<\/sup>+bx<sup>2<\/sup>+cx+b= 0, cuyo tama\u00f1o se hace m\u00e1s peque\u00f1o a medida que el polinomio se hace m\u00e1s complejo (intuitivamente, esto se relaciona con que a,b y c se hacen m\u00e1s grandes, pero en realidad es la ra\u00edz c\u00fabica del discriminante). El punto hacia el que parece atraer toda la imagen es i, la ra\u00edz cuadrada de -1. <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">P\u00f3lya Wallpaper groups<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"747\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/polya-wallpaper-groups-4-mathemalchemy-art-installation.jpg?resize=747%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4665\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/polya-wallpaper-groups-4-mathemalchemy-art-installation.jpg?resize=747%2C1024&amp;ssl=1 747w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/polya-wallpaper-groups-4-mathemalchemy-art-installation.jpg?resize=219%2C300&amp;ssl=1 219w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/polya-wallpaper-groups-4-mathemalchemy-art-installation.jpg?resize=768%2C1053&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/polya-wallpaper-groups-4-mathemalchemy-art-installation.jpg?w=802&amp;ssl=1 802w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>En 1924, George P\u00f3lya public\u00f3 un art\u00edculo en <em>Zeitschrift f\u00fcr Kristallographie<\/em> en el que demostraba que existen exactamente diecisiete grupos de papel tapiz. En otras palabras, si observa usted dise\u00f1os en el plano que se repiten en dos direcciones no paralelas, como los de la pared lateral de la panader\u00eda y los de la pared trasera de la tienda de curiosidades, todos tienen una de las diecisiete estructuras de simetr\u00eda diferentes. Esta figura de su trabajo muestra una imagen representativa de cada grupo de papel tapiz.  <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>En aquel momento, P\u00f3lya ignoraba felizmente que Evgraf Federov ya hab\u00eda demostrado este teorema 33 a\u00f1os antes. No obstante, el art\u00edculo de 1924 tuvo un impacto duradero en la cultura matem\u00e1tica. Al principio de su carrera art\u00edstica, M.C. Escher se top\u00f3 con el art\u00edculo de P\u00f3lya y su diagrama de clasificaci\u00f3n, que coincid\u00eda con las exploraciones del propio Escher sobre las teselaciones regulares del plano. Como documenta la matem\u00e1tica y bi\u00f3grafa de Escher, Doris Schattschneider, Escher copi\u00f3 cada una de las teselaciones de P\u00f3lya en sus cuadernos, las estudi\u00f3 detenidamente y comparti\u00f3 su admiraci\u00f3n y gratitud en las cartas que intercambi\u00f3 con P\u00f3lya.   <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Page from Henry\u2019s Notebook<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/page-from-henry-segerman-notebook-5-mathemalchemy-art-installation.jpg?resize=791%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4675\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/page-from-henry-segerman-notebook-5-mathemalchemy-art-installation.jpg?resize=791%2C1024&amp;ssl=1 791w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/page-from-henry-segerman-notebook-5-mathemalchemy-art-installation.jpg?resize=232%2C300&amp;ssl=1 232w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/page-from-henry-segerman-notebook-5-mathemalchemy-art-installation.jpg?resize=768%2C994&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/page-from-henry-segerman-notebook-5-mathemalchemy-art-installation.jpg?w=850&amp;ssl=1 850w\" sizes=\"auto, (max-width: 791px) 100vw, 791px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>\u00c9sta es una p\u00e1gina de notas de <a href=\"https:\/\/mathemalchemy.org\/es\/equipo-de-matemalquimia\/#Henry-Segerman\">Henry<\/a> Segerman, en la que se recoge una discusi\u00f3n con Saul Schleimer sobre una prueba que acab\u00f3 public\u00e1ndose en <em>Essential loops in taut ideal triangulations,<\/em> de Saul Schleimer y Henry Segerman, <em>Algebraic and Geometric Topology,<\/em> 20 (2020), n\u00ba 1, 487-501. El objetivo es demostrar que en una variedad tridimensional con una t<em>riangulaci\u00f3n ideal tensa<\/em> (las superficies dibujadas en negro), ciertas curvas de la superficie<em>(curvas normales,<\/em> dibujadas en verde), no pueden delimitar un disco en la variedad. El argumento utiliza el concepto de <em>\u00edndice<\/em> de una superficie, que est\u00e1 estrechamente relacionado con la caracter\u00edstica de Euler.<\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Gauss\u2019s Eureka Theorem concisely written in his diary<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gauss-eureka-theorem-concisely-written-in-diary-6-mathemalchemy-art-installation.jpg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-4677\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gauss-eureka-theorem-concisely-written-in-diary-6-mathemalchemy-art-installation.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gauss-eureka-theorem-concisely-written-in-diary-6-mathemalchemy-art-installation.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gauss-eureka-theorem-concisely-written-in-diary-6-mathemalchemy-art-installation.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gauss-eureka-theorem-concisely-written-in-diary-6-mathemalchemy-art-installation.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gauss-eureka-theorem-concisely-written-in-diary-6-mathemalchemy-art-installation.jpg?resize=200%2C150&amp;ssl=1 200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta p\u00e1gina pertenece al diario matem\u00e1tico de Gauss; podemos ver su anotaci\u00f3n de lo que se conoci\u00f3 como el Teorema Eureka de Gauss. El teorema afirma que todo n\u00famero entero positivo puede expresarse como la suma de tres n\u00fameros triangulares. Un n\u00famero es triangular si cuenta el n\u00famero de puntos de una red triangular que caen dentro de un tri\u00e1ngulo equil\u00e1tero. Cuanto mayor sea el tri\u00e1ngulo, mayor ser\u00e1 el n\u00famero triangular; los 6 primeros n\u00fameros triangulares son 0,1,3,6,10,15.    <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>En la hoja se puede leer, de pu\u00f1o y letra de Gauss,<\/p>\n\n\n\n<p class=\"has-text-align-center has-primary-color has-text-color has-lora-font-family has-large-font-size has-custom-font\" style=\"font-family:Lora\">EYPHKA: num = \u0394 + \u0394 + \u0394<\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">2D-3D hyperbolic plane<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"832\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/2d-3d-hyperbolic-plane-7-mathemalchemy-art-installation.jpg?resize=832%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4680\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/2d-3d-hyperbolic-plane-7-mathemalchemy-art-installation.jpg?resize=832%2C1024&amp;ssl=1 832w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/2d-3d-hyperbolic-plane-7-mathemalchemy-art-installation.jpg?resize=244%2C300&amp;ssl=1 244w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/2d-3d-hyperbolic-plane-7-mathemalchemy-art-installation.jpg?resize=768%2C945&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/2d-3d-hyperbolic-plane-7-mathemalchemy-art-installation.jpg?w=894&amp;ssl=1 894w\" sizes=\"auto, (max-width: 832px) 100vw, 832px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>La imagen de esta hoja ilustra varios aspectos del plano hiperb\u00f3lico en una visualizaci\u00f3n combinada. De izquierda a derecha, muestra (parte de) una teselaci\u00f3n del disco de Poincar\u00e9 mediante tri\u00e1ngulos regulares (hiperb\u00f3licos), luego una subdivisi\u00f3n en tri\u00e1ngulos hiperb\u00f3licos m\u00e1s peque\u00f1os de la triangulaci\u00f3n en la que algunos de estos tri\u00e1ngulos m\u00e1s peque\u00f1os est\u00e1n coloreados de amarillo para generar un bonito patr\u00f3n. <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Cerca de la derecha, esta triangulaci\u00f3n \u00abse eleva\u00bb en una visualizaci\u00f3n tridimensional que muestra todos los tri\u00e1ngulos peque\u00f1os como iguales en tama\u00f1o euclidiano, lo que requiere muchos \u00abvolantes\u00bb en la superficie para proporcionar \u00e1rea suficiente para acomodarlos a todos &#8211; esto recuerda a los modelos de ganchillo de geometr\u00eda hiperb\u00f3lica del <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/jardin-conexiones-matematicas\/\">Jard\u00edn<\/a> y el <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/bahia-de-nudos-conexiones-matematicas\/\">Arrecife<\/a>.<\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Farey sequences and Ford circles<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<figure class=\"wp-block-image size-large\" id=\"Farey-sequences-and-Ford-circles\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"452\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/farey-sequences-and-ford-circles-8-mathemalchemy-art-installation.jpg?resize=900%2C452&#038;ssl=1\" alt=\"Secuencias de Farey y c&#xED;rculos de Ford\" class=\"wp-image-4685\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/farey-sequences-and-ford-circles-8-mathemalchemy-art-installation.jpg?resize=1024%2C514&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/farey-sequences-and-ford-circles-8-mathemalchemy-art-installation.jpg?resize=300%2C151&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/farey-sequences-and-ford-circles-8-mathemalchemy-art-installation.jpg?resize=768%2C386&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/farey-sequences-and-ford-circles-8-mathemalchemy-art-installation.jpg?resize=1200%2C603&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/farey-sequences-and-ford-circles-8-mathemalchemy-art-installation.jpg?w=1334&amp;ssl=1 1334w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>La secuencia de Farey de orden <em>N<\/em> es la colecci\u00f3n ordenada linealmente de todas las fracciones del tipo <em>p<\/em>\/<em>q<\/em>, en la que <em>p<\/em> y <em>q<\/em> son enteros positivos primos entre s\u00ed, con <em>p<\/em> entre 1 y <em>q-1<\/em>, y <em>q<\/em> no superior a <em>N<\/em>. Las secuencias de Farey tienen propiedades matem\u00e1ticas sorprendentemente sofisticadas para objetos tan mundanos. La figura de la hoja ilustra las relaciones entre las secuencias de Farey de bajo orden y c\u00edrculos del tamiz de Apolonio situados entre el eje horizontal y los dos c\u00edrculos con radio \u00bd y centros en (0, \u00bd) y (1, \u00bd) respectivamente.  <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Mice illustrating a dihedral group<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"668\" height=\"850\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mice-illustrating-a-dihedral-group-9-mathemalchemy-art-installation.jpg?resize=668%2C850&#038;ssl=1\" alt=\"\" class=\"wp-image-4686\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mice-illustrating-a-dihedral-group-9-mathemalchemy-art-installation.jpg?w=668&amp;ssl=1 668w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mice-illustrating-a-dihedral-group-9-mathemalchemy-art-installation.jpg?resize=236%2C300&amp;ssl=1 236w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Un grupo diedral es el grupo de simetr\u00edas de un <em>n<\/em>-\u00e1gono regular. En otras palabras, es un sistema aritm\u00e9tico construido a partir de las 2<em>n<\/em> formas distintas de girar y reflejar el <em>n<\/em>-\u00e1gono; en este sistema, podemos combinar pares de movimientos igual que podemos, por ejemplo, sumar pares de n\u00fameros. <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Esta l\u00e1mina (o m\u00e1s bien colecci\u00f3n de peque\u00f1as l\u00e1minas) muestra concretamente la acci\u00f3n de las simetr\u00edas del grupo diedral del cuadrado, llamado <em>D<\/em><sub>4<\/sub> por unos (ge\u00f3metras, porque est\u00e1 constituido por las simetr\u00edas del 4-\u00e1gono) o <em>D<\/em><sub>8<\/sub> por otros (algebristas, porque el grupo tiene 8 elementos). El rat\u00f3n de MatemAlquimia de las <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/tienda-de-curiosidades-conexiones-matematicas\/#mats-wallpaper-groups\">alfombrillas de la Tienda de Curiosidades<\/a> sufre reflejos y rotaciones en abundancia, cada uno indicado por su propio color. Las rotaciones puras tienen varios tonos de rosa\/rojo; un reflejo a\u00f1ade algo de azul. La gran tabla coloreada muestra la tabla de multiplicar (o tabla de Cayley) del grupo; otras figuras muestran la estructura de subgrupos de este grupo diedral.   <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Galois<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"622\" height=\"800\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/galois-10-mathemalchemy-art-installation.jpg?resize=622%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-4691\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/galois-10-mathemalchemy-art-installation.jpg?w=622&amp;ssl=1 622w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/galois-10-mathemalchemy-art-installation.jpg?resize=233%2C300&amp;ssl=1 233w\" sizes=\"auto, (max-width: 622px) 100vw, 622px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta p\u00e1gina muestra dos ret\u00edculos cuya relaci\u00f3n demuestra el <strong>Teorema Fundamental de la Teor\u00eda de Galois<\/strong>: el ret\u00edculo de campos intermedios de la extensi\u00f3n de campos Q(\u221c2, <em>i)<\/em>\/Q es una versi\u00f3n invertida del ret\u00edculo de <em>subgrupos<\/em> del grupo de <strong>Galois <\/strong>de la extensi\u00f3n, D<sub>8<\/sub>. Detr\u00e1s de estos dos ret\u00edculos se encuentra un retrato de \u00c9variste Galois. <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Fano plane<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<p id=\"fano-planes\">El plano de Fano es el plano proyectivo finito m\u00e1s peque\u00f1o; s\u00f3lo tiene 7 puntos. En un plano proyectivo cada dos puntos determinan una \u00fanica recta que pasa por ambos puntos, y cada dos rectas se intersecan en un \u00fanico punto. El plano de Fano tiene 3 puntos en cada una de sus 7 rectas, y 3 rectas que pasan por cada uno de sus 7 puntos.    <\/p>\n\n\n\n<p id=\"fano-planes\">Para hacer un dibujo de esto en un plano eucl\u00eddeo, algunas de las rectas tienen que dibujarse definitivamente no rectas. La figura de la derecha muestra mejor las simetr\u00edas, a costa de que ninguna l\u00ednea parezca recta. La figura de la izquierda tambi\u00e9n funciona como mnemotecnia para la tabla de multiplicar de los <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/mural-conexiones-matematicas\/\">octoniones<\/a>.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"427\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/fano-plane-11-mathemalchemy-art-installation.jpg?resize=900%2C427&#038;ssl=1\" alt=\"\" class=\"wp-image-4695\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/fano-plane-11-mathemalchemy-art-installation.jpg?resize=1024%2C486&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/fano-plane-11-mathemalchemy-art-installation.jpg?resize=300%2C143&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/fano-plane-11-mathemalchemy-art-installation.jpg?resize=768%2C365&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/fano-plane-11-mathemalchemy-art-installation.jpg?resize=1200%2C570&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/fano-plane-11-mathemalchemy-art-installation.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Additive Mixing<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<figure class=\"wp-block-image size-large\" id=\"additive-mixing-cavalcade\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/additive-mixing-12-mathemalchemy-art-installation.jpg?resize=900%2C506&#038;ssl=1\" alt=\"\" class=\"wp-image-4696\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/additive-mixing-12-mathemalchemy-art-installation.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/additive-mixing-12-mathemalchemy-art-installation.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/additive-mixing-12-mathemalchemy-art-installation.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/additive-mixing-12-mathemalchemy-art-installation.jpg?resize=1200%2C675&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/additive-mixing-12-mathemalchemy-art-installation.jpg?w=1400&amp;ssl=1 1400w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Este diagrama de Venn ilustra las conexiones entre las matem\u00e1ticas, el arte y la abstracci\u00f3n; las im\u00e1genes asociadas a cada regi\u00f3n corresponden a la caracterizaci\u00f3n de la regi\u00f3n como conjunto. La regi\u00f3n de s\u00f3lo Matem\u00e1ticas presenta l\u00edneas secantes y tangentes (conceptos clave del c\u00e1lculo diferencial), la intersecci\u00f3n de s\u00f3lo los c\u00edrculos de Matem\u00e1ticas y Abstracci\u00f3n contiene un diagrama conmutativo, y la intersecci\u00f3n de los tres c\u00edrculos contiene una adaptaci\u00f3n del teselado 30-45-90 de Coxeter del plano hiperb\u00f3lico, un dise\u00f1o abstracto que atrae a matem\u00e1ticos y artistas. La regi\u00f3n de Matem\u00e1ticas y Arte presenta un mosaico de patrones de peces al estilo de Escher, creado por Bronna Butler; algunos de los peces nadan hacia la regi\u00f3n de s\u00f3lo Arte, y luego escapan por completo del diagrama de Venn. El t\u00edtulo se refiere a c\u00f3mo los colores de las intersecciones de los c\u00edrculos se crean a partir de los colores de las regiones de conjunto \u00fanico. Hay distintas formas de mezclar los colores; la \u00ab<a href=\"http:\/\/en.wikipedia.org\/wiki\/Additive_color\">mezcla aditiva<\/a>\u00bb se refiere al proceso de mezclar colores utilizando dos o m\u00e1s haces de luz de distinto color. El rojo, el azul y el verde llenan las regiones de un solo sujeto; sus mezclas aditivas por pares magenta, amarillo y cian llenan las intersecciones de 2 regiones; y la mezcla aditiva de los tres colores originales forma el blanco del centro del diagrama . Esta obra fue seleccionada para la <a href=\"http:\/\/gallery.bridgesmathart.org\/exhibitions\/2021-joint-mathematics-meetings\/sklarjk\">Galer\u00eda de Arte Matem\u00e1tico de la Reuni\u00f3n Conjunta de Matem\u00e1ticas<\/a> de 2021, y puede ver el siguiente v\u00eddeo sobre ella en Vimeo.      <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Additive Mixing\" src=\"https:\/\/player.vimeo.com\/video\/496667864?dnt=1&amp;app_id=122963\" width=\"900\" height=\"506\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe>\n<\/div><\/figure>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Koch snowflakes<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"789\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/koch-snowflakes-13-mathemalchemy-art-installation.jpg?resize=789%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4701\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/koch-snowflakes-13-mathemalchemy-art-installation.jpg?resize=789%2C1024&amp;ssl=1 789w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/koch-snowflakes-13-mathemalchemy-art-installation.jpg?resize=231%2C300&amp;ssl=1 231w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/koch-snowflakes-13-mathemalchemy-art-installation.jpg?resize=768%2C996&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/koch-snowflakes-13-mathemalchemy-art-installation.jpg?w=848&amp;ssl=1 848w\" sizes=\"auto, (max-width: 789px) 100vw, 789px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>El Copo de Nieve de Koch es un ejemplo cl\u00e1sico de l\u00ednea fractal. Puede ver aqu\u00ed una construcci\u00f3n geom\u00e9trica sencilla, utilizando tri\u00e1ngulos; esto da lugar a una curva que se mantiene igual de ondulada a medida que se acerca uno a ella, lo que significa que no hay ninguna tangente bien definida en ninguna parte de la curva. Agradablemente, la curva resultante puede encajarse sobre s\u00ed misma a diferentes tama\u00f1os, creando adoquinados de una misma forma, pero a diferentes tama\u00f1os, como tambi\u00e9n se muestra aqu\u00ed.  <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Prime number race<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"781\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/prime-number-race-14-mathemalchemy-art-installation.jpg?resize=781%2C1024&#038;ssl=1\" alt=\"Hoja de carrera de n&#xFA;meros primos en la Cabalgata\" class=\"wp-image-4708\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/prime-number-race-14-mathemalchemy-art-installation.jpg?resize=781%2C1024&amp;ssl=1 781w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/prime-number-race-14-mathemalchemy-art-installation.jpg?resize=229%2C300&amp;ssl=1 229w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/prime-number-race-14-mathemalchemy-art-installation.jpg?resize=768%2C1007&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/prime-number-race-14-mathemalchemy-art-installation.jpg?w=839&amp;ssl=1 839w\" sizes=\"auto, (max-width: 781px) 100vw, 781px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta hoja se relaciona con las ardillas en el jard\u00edn que exploran los n\u00fameros primos con la Criba de Erat\u00f3stenes. A medida que encuentran los primos, las ardillas pueden notar que ciertas columnas de su tabla tienen m\u00e1s primos mientras que otras tienen menos. Podr\u00edan preguntarse c\u00f3mo se distribuyen los primos en estas columnas, lo que equivale a preguntar: \u00bfcu\u00e1ntos primos tienen, en nuestra notaci\u00f3n est\u00e1ndar en base 10, un \u00faltimo d\u00edgito igual a uno de los 10 valores posibles, 0, 1, 2, \u2026, 9?<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Por supuesto, algunas cifras finales, como el 4, no pueden aparecer en ning\u00fan primo. Cualquier n\u00famero que acabe en 4, 6 u 8 es divisible por 2 y, por tanto, no es primo. Adem\u00e1s, s\u00f3lo hay un n\u00famero primo que termine en 2 (el propio 2), y s\u00f3lo hay un n\u00famero primo que termine en 5 (el propio 5). As\u00ed que las ardillas podr\u00edan preguntarse en realidad: \u00bfcu\u00e1ntos primos terminan en 1 o en 3, 7, 9? \u00bfHay m\u00e1s de unos que de otros?    <\/p>\n\n\n\n<p>La respuesta a esta pregunta es un tanto sorprendente y misteriosa. Por un lado, el Teorema de Dirichlet sobre los primos en progresiones aritm\u00e9ticas dice que a largo plazo (es decir, a medida que llevamos al l\u00edmite infinito los tama\u00f1os de los primos que estamos considerando), los primos se distribuyen uniformemente entre estas cuatro posibilidades. En cambio, si nos detenemos en cualquier punto finito, \u00a1parece que hay m\u00e1s primos que terminan en 3 o en 7 que primos que terminan en 1 o en 9! La hoja muestra algunos datos que ilustran este fen\u00f3meno. Aunque se ha demostrado que el Equipo 3 y 7 mantiene la ventaja durante gran parte del tiempo, el Equipo 1 y 9 toma la delantera infinitamente a menudo. Comprender exactamente esta carrera (y otras similares) sigue siendo un \u00e1rea de investigaci\u00f3n activa.     <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Proofs without words<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"524\" height=\"746\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/proof-without-words-15-mathemalchemy-art-installation.jpg?resize=524%2C746&#038;ssl=1\" alt=\"Hoja de prueba sin palabras\" class=\"wp-image-4709\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/proof-without-words-15-mathemalchemy-art-installation.jpg?w=524&amp;ssl=1 524w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/proof-without-words-15-mathemalchemy-art-installation.jpg?resize=211%2C300&amp;ssl=1 211w\" sizes=\"auto, (max-width: 524px) 100vw, 524px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Dos demostraciones sin palabras. La imagen superior muestra que la suma de los cubos de los n\u00fameros del 1 al nnn es igual al cuadrado de 1+2+\u22ef+n1+2+\\cdots+n1+2+\u22ef+n. La inferior muestra que 3 veces la suma infinita 1\/4+(1\/4)<sup>2<\/sup>+\u22ef+(1\/4)n+\u22efes igual a 1; este dibujo tambi\u00e9n aparece como un ejemplo de series que convergen geom\u00e9tricamente en una cr\u00f3nica titulada<br\/><a href=\"https:\/\/mathemalchemy.org\/es\/2021\/02\/02\/arcos-de-pelotas-convergentes-y-divergentes\/\">Arcos de Bolas Convergentes y Divergentes.<\/a>  <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">David Henderson\u2019s Theorem<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4715\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=900%2C1200&amp;ssl=1 900w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?resize=1200%2C1601&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/david-henderson-s-heorem-16-mathemalchemy-art-installation.jpg?w=1312&amp;ssl=1 1312w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Al dibujar un diagrama en una hoja de papel bidimensional, para 3 conjuntos contenidos todos ellos en un conjunto mayor S, en el que cada uno de los 3 conjuntos est\u00e1 representado por un c\u00edrculo y la propia hoja representa a S, es f\u00e1cil disponer los c\u00edrculos de forma que el diagrama muestre las ocho posibilidades de un elemento de S (podr\u00eda no pertenecer a ninguno de los tres conjuntos menores; hay 3 formas en las que podr\u00eda pertenecer a un conjunto menor pero no a los otros dos; hay de nuevo 3 formas en las que pertenece a dos conjuntos menores pero no al tercero; por \u00faltimo, podr\u00eda pertenecer a los tres). Esto se llama diagrama de Venn; adem\u00e1s, para 3 conjuntos es f\u00e1cil disponer los c\u00edrculos sim\u00e9tricamente.   <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Ya para 4 conjuntos no es posible dibujar un diagrama de Venn (que ahora mostrar\u00eda 2<sup>4<\/sup> = 16 regiones) en el que el l\u00edmite de cada uno de los 4 conjuntos fuera un c\u00edrculo: hay que considerar otras formas, y sustituir los c\u00edrculos por curvas de Jordan m\u00e1s generales.<\/p>\n\n\n\n<p>Si se impone que cada una de las 2<sup>4<\/sup> regiones sea conexa, entonces no es posible una disposici\u00f3n sim\u00e9trica: las cuatro curvas de Jordan no pueden ser simplemente la misma curva en cuatro versiones, obtenidas girando la misma plantilla para las cuatro. El teorema de David Henderson afirma que un diagrama de Venn para N conjuntos en el que todas las 2<sup>N<\/sup> posibilidades est\u00e1n representadas por regiones conectadas, con cada uno de los N conjuntos delimitado por una curva de Jordan, puede tener simetr\u00eda rotacional si y s\u00f3lo si N es primo. La hoja muestra algunos de los dibujos preliminares realizados por David Henderson cuando trabajaba en esto, y algunos dibujos del diagrama de Venn con simetr\u00eda rotacional para N primo peque\u00f1o. <a href=\"https:\/\/www-users.cse.umn.edu\/~webb\/Publications\/WebbWagonVennNote8.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Este documento<\/a> contiene una buena discusi\u00f3n y tambi\u00e9n se\u00f1ala y corrige una deficiencia en la demostraci\u00f3n original.  <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Dehn Lemma extension<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<p>Esta ficha ilustra una forma geom\u00e9trica de ver y extender <a href=\"http:\/\/en.wikipedia.org\/wiki\/Dehn's_lemma\" target=\"_blank\" rel=\"noreferrer noopener\">el Lema de Dehn<\/a>. El lema de Dehn afirma que un mapeo lineal a trozos de un disco a una 3-variedad, con la singularidad del mapeo situada en el interior del disco, implica la existencia de otro mapeo lineal a trozos del disco que es un encaje y es id\u00e9ntico al original en el l\u00edmite del disco. La demostraci\u00f3n de este teorema tiene una historia curiosa: se cre\u00eda demostrado por Max Dehn en 1910, hasta que Hellmuth Kneser encontr\u00f3 una laguna en la demostraci\u00f3n en 1929; su estatus qued\u00f3 entonces en entredicho hasta que Christos Papakyriakopoulos demostr\u00f3 una generalizaci\u00f3n en 1957, ahora llamada teorema del bucle. Este resultado fue inmensamente importante en el desarrollo de la topolog\u00eda de los 3 espacios. Una nueva extensi\u00f3n en 1965, en la tesis doctoral de David Henderson, fue el resultado de su interpretaci\u00f3n m\u00e1s geom\u00e9trica, en la que la cuesti\u00f3n se reformul\u00f3 como <em>tomar un disco singular dado cuyo interior no intersecara el l\u00edmite, \u00abcambiarlo\u00bb por un disco no singular que tuviera ciertas propiedades deseadas en com\u00fan con el disco singular original.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"695\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/dehn-lemma-extension-17-mathemalchemy-art-installation.jpg?resize=900%2C695&#038;ssl=1\" alt=\"\" class=\"wp-image-4719\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/dehn-lemma-extension-17-mathemalchemy-art-installation.jpg?resize=1024%2C791&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/dehn-lemma-extension-17-mathemalchemy-art-installation.jpg?resize=300%2C232&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/dehn-lemma-extension-17-mathemalchemy-art-installation.jpg?resize=768%2C593&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/dehn-lemma-extension-17-mathemalchemy-art-installation.jpg?w=1100&amp;ssl=1 1100w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div><\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Extension of Pythagoras for arbitrary triangles<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<p>El mismo argumento utilizado en la demostraci\u00f3n geom\u00e9trica tradicional del teorema de Pit\u00e1goras [(1) dejando caer perpendiculares desde cada v\u00e9rtice de un tri\u00e1ngulo sobre el lado opuesto, y continu\u00e1ndolas en el cuadrado construido sobre el lado, y luego (2) mostrando la igualdad de \u00e1reas de rect\u00e1ngulos mostrando la congruencia de tri\u00e1ngulos que tienen exactamente la mitad del \u00e1rea de cada uno de esos rect\u00e1ngulos], puede utilizarse para tri\u00e1ngulos arbitrarios (en lugar de rect\u00e1ngulos) y conduce a una interesante observaci\u00f3n que ampl\u00eda el teorema de Pit\u00e1goras y hace que el argumento sea m\u00e1s sim\u00e9trico. Sin duda, \u00a1algo que celebrar para los tri\u00e1ngulos convertidos en mariposas! <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"664\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/extension-of-pythagoras-for-arbitrary-triangles-18-mathemalchemy-art-installation.jpg?resize=900%2C664&#038;ssl=1\" alt=\"\" class=\"wp-image-4722\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/extension-of-pythagoras-for-arbitrary-triangles-18-mathemalchemy-art-installation.jpg?resize=1024%2C755&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/extension-of-pythagoras-for-arbitrary-triangles-18-mathemalchemy-art-installation.jpg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/extension-of-pythagoras-for-arbitrary-triangles-18-mathemalchemy-art-installation.jpg?resize=768%2C566&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/extension-of-pythagoras-for-arbitrary-triangles-18-mathemalchemy-art-installation.jpg?resize=1200%2C885&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/extension-of-pythagoras-for-arbitrary-triangles-18-mathemalchemy-art-installation.jpg?w=1256&amp;ssl=1 1256w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Knot-to-link-to-knot<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knot-to-link-to-knot-19-mathemalchemy-art-installation.jpg?resize=791%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4724\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knot-to-link-to-knot-19-mathemalchemy-art-installation.jpg?resize=791%2C1024&amp;ssl=1 791w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knot-to-link-to-knot-19-mathemalchemy-art-installation.jpg?resize=232%2C300&amp;ssl=1 232w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knot-to-link-to-knot-19-mathemalchemy-art-installation.jpg?resize=768%2C994&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knot-to-link-to-knot-19-mathemalchemy-art-installation.jpg?w=850&amp;ssl=1 850w\" sizes=\"auto, (max-width: 791px) 100vw, 791px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>La gente que hace acolchados (quilts) tiene muchos dise\u00f1os interesantes de anillos con intrincadas vueltas. Esta hoja muestra que algunos de estos dise\u00f1os pueden reconstruirse siguiendo sencillas reglas algor\u00edtmicas, partiendo de dise\u00f1os mucho m\u00e1s simples. <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n<\/div>\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Martin Gardner mathematical games<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\" id=\"Martin-Gardner-mathematical-games\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/martin-gardner-mathematical-games-20-mathemalchemy-art-installation.jpg?resize=597%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4727\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/martin-gardner-mathematical-games-20-mathemalchemy-art-installation.jpg?resize=597%2C1024&amp;ssl=1 597w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/martin-gardner-mathematical-games-20-mathemalchemy-art-installation.jpg?resize=175%2C300&amp;ssl=1 175w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/martin-gardner-mathematical-games-20-mathemalchemy-art-installation.jpg?w=641&amp;ssl=1 641w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Durante 25 a\u00f1os, Martin Gardner escribi\u00f3 la columna \u00abJuegos matem\u00e1ticos\u00bb para la revista <em>Scientific American<\/em>. Fue la columna m\u00e1s popular de la revista. La red poli\u00e9drica desplegada de un octaedro truncado incluye ocho caras hexagonales con dise\u00f1os relacionados con temas de las populares columnas: el juego de Hex, una banda de M\u00f6bius, un mosaico de Penrose, una pistola planeadora de Gosper del <em>Juego de la Vida<\/em> de John Conway , el hexaflex\u00e1gono de Stone, los copos de nieve cuadrados de Mandelbrot, \u00abEl beso preciso\u00bb de Soddy y los pentomin\u00f3s de Golomb.  <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Minkowski primes<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<p>Fermat demostr\u00f3 este hermoso hecho: que cualquier n\u00famero primo que sea 1 mod 4 puede escribirse como la suma de dos cuadrados y, a la inversa, si un primo impar puede escribirse como la suma de dos cuadrados, debe ser 1 mod 4. Aqu\u00ed vemos una demostraci\u00f3n diferente de este hecho que utiliza el Teorema de Minkowski, que afirma que, dada una red, cualquier regi\u00f3n convexa que sea sim\u00e9trica respecto al origen y tenga \u00e1rea suficiente debe contener un punto de red adem\u00e1s del origen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"613\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/minkowski-primes-21-mathemalchemy-art-installation.jpg?resize=900%2C613&#038;ssl=1\" alt=\"\" class=\"wp-image-4730\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/minkowski-primes-21-mathemalchemy-art-installation.jpg?resize=1024%2C698&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/minkowski-primes-21-mathemalchemy-art-installation.jpg?resize=300%2C204&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/minkowski-primes-21-mathemalchemy-art-installation.jpg?resize=768%2C523&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/minkowski-primes-21-mathemalchemy-art-installation.jpg?resize=1200%2C818&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/minkowski-primes-21-mathemalchemy-art-installation.jpg?w=1256&amp;ssl=1 1256w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Tetrahedral kites and Sierpi\u0144ski<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\" id=\"tetrahedral-kit-and-Sierpinski\"><a href=\"en.wikipedia.org\/wiki\/ Tetrahedral_kite\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tetrahedral-kites-and-sierpinski-22-mathemalchemy-art-installation.jpg?resize=720%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4754\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tetrahedral-kites-and-sierpinski-22-mathemalchemy-art-installation.jpg?resize=720%2C1024&amp;ssl=1 720w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tetrahedral-kites-and-sierpinski-22-mathemalchemy-art-installation.jpg?resize=211%2C300&amp;ssl=1 211w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tetrahedral-kites-and-sierpinski-22-mathemalchemy-art-installation.jpg?resize=768%2C1093&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tetrahedral-kites-and-sierpinski-22-mathemalchemy-art-installation.jpg?w=1000&amp;ssl=1 1000w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><a href=\"http:\/\/en.wikipedia.org\/wiki\/Tetrahedral_kite\">Los papalotes tetra\u00e9dricos<\/a> fueron propuestos por primera vez por Alexander Graham Bell (quiz\u00e1 m\u00e1s famoso por su trabajo pionero sobre el tel\u00e9fono); la hoja muestra el t\u00edtulo de su art\u00edculo sobre el tema. Este tipo de papalote tiene velas que atrapan el viento en varios \u00e1ngulos sobre un esqueleto muy estable: la regularidad del tetraedro da lugar a una forma fuerte con un buen equilibrio de la carga.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Bell pas\u00f3 r\u00e1pidamente de un modelo de tetraedro \u00fanico a otro con varias celdas, e incluso los primeros ya mostraban un dise\u00f1o \u00abtipo fractal\u00bb que recordaba al<a href=\"http:\/\/en.wikipedia.org\/wiki\/Sierpi%C5%84ski_triangle\" target=\"_blank\" rel=\"noreferrer noopener\"> tri\u00e1ngulo de Sierpi\u0144ski <\/a>bidimensional. Este tri\u00e1ngulo tambi\u00e9n est\u00e1 \u00aboculto\u00bb en el<a href=\"http:\/\/en.wikipedia.org\/wiki\/Pascal's_triangle\" target=\"_blank\" rel=\"noreferrer noopener\"> tri\u00e1ngulo de Pascal:<\/a> \u00a1s\u00f3lo tiene que marcar las posiciones de los n\u00fameros impares!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"872\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/800px-Early_design_of_a_Tetrahedron_kite_cell_by_Alexander_Graham_Bell.jpg?resize=800%2C872&#038;ssl=1\" alt=\"\" class=\"wp-image-10829\" style=\"width:362px;height:394px\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/800px-Early_design_of_a_Tetrahedron_kite_cell_by_Alexander_Graham_Bell.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/800px-Early_design_of_a_Tetrahedron_kite_cell_by_Alexander_Graham_Bell.jpg?resize=275%2C300&amp;ssl=1 275w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/05\/800px-Early_design_of_a_Tetrahedron_kite_cell_by_Alexander_Graham_Bell.jpg?resize=768%2C837&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\"><strong>Uno de los primeros papalotes tetra\u00e9dricos de Alexander Bell.<\/strong><\/figcaption><\/figure>\n<\/div><\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Bouligand Hopf fibration<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"894\" height=\"1000\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bouligand-hopf-fibration-23-mathemalchemy-art-installation.jpg?resize=894%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-4756\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bouligand-hopf-fibration-23-mathemalchemy-art-installation.jpg?w=894&amp;ssl=1 894w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bouligand-hopf-fibration-23-mathemalchemy-art-installation.jpg?resize=268%2C300&amp;ssl=1 268w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bouligand-hopf-fibration-23-mathemalchemy-art-installation.jpg?resize=768%2C859&amp;ssl=1 768w\" sizes=\"auto, (max-width: 894px) 100vw, 894px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta figura est\u00e1 tomada del trabajo de <a href=\"http:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3438575\/\" target=\"_blank\" rel=\"noreferrer noopener\">Yves Bouligand<\/a>, un bi\u00f3logo franc\u00e9s que mostr\u00f3 sorprendentes conexiones entre las estructuras que se encuentran en el mundo vivo y su morfog\u00e9nesis, las estructuras inertes (no vivas) en f\u00edsica en, por ejemplo, los cristales l\u00edquidos, y las construcciones en geometr\u00eda y topolog\u00eda. Esta figura en particular ilustra el papel de la fibraci\u00f3n de Hopf en las estructuras de col\u00e1geno.<\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Pythagoras without words<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"624\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/pyhtagoras-without-words-24-mathemalchemy-art-installation.jpg?resize=624%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4758\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/pyhtagoras-without-words-24-mathemalchemy-art-installation.jpg?resize=624%2C1024&amp;ssl=1 624w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/pyhtagoras-without-words-24-mathemalchemy-art-installation.jpg?resize=183%2C300&amp;ssl=1 183w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/pyhtagoras-without-words-24-mathemalchemy-art-installation.jpg?w=670&amp;ssl=1 670w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Aqu\u00ed tiene una demostraci\u00f3n ilustrada del Teorema de Pit\u00e1goras que ha circulado mucho. La prueba se basa en dos disecciones de un cuadrado de lado a+b. Cada una de ellas contiene cuatro tri\u00e1ngulos rect\u00e1ngulos congruentes de lados a, b y c; en la primera, el \u00e1rea restante est\u00e1 formada por dos cuadrados de \u00e1rea total a<sup>2<\/sup> + b<sup>2<\/sup>, y en la segunda, el \u00e1rea restante es un \u00fanico cuadrado de \u00e1rea c<sup>2<\/sup>. Restando el \u00e1rea de los cuatro tri\u00e1ngulos del \u00e1rea del cuadrado (a+b)-, obtenemos que a<sup>2<\/sup> + b<sup>2<\/sup> = c<sup>2<\/sup>, como se deseaba. Aunque pruebas de disecci\u00f3n similares con algo m\u00e1s de \u00e1lgebra se conocen desde hace muchos siglos, esta prueba parece haber sido descubierta por un estudiante de bachillerato en la d\u00e9cada de 1930.    <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n<\/div>\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Emmy Noether<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\" id=\"emmy-noether\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Emmy Noether fue, seg\u00fan todos los testimonios, una matem\u00e1tica asombrosa, adem\u00e1s de una persona divertida: su foto favorita era una en la que aparece en un barco, ri\u00e9ndose del fot\u00f3grafo.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\" id=\"Emmy-Noether\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/cdn.arstechnica.net\/wp-content\/uploads\/2015\/05\/Schiffsbild.jpg?w=900&#038;ssl=1\" alt=\"\" title=\"Emmy Noether\"\/><figcaption class=\"wp-element-caption\">Emmy Noether &#8211; \ud83d\udcf7 <a href=\"http:\/\/arstechnica.com\/science\/%202015\/05\/the-female-mathematician-who-changed-the-course-%20of-physics-but-couldnt-get-a-job\/\" target=\"_blank\" rel=\"noreferrer noopener\">arstechnica.com<\/a><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>El boceto que aparece aqu\u00ed fue realizado por Stephanie Magdziak, como preparaci\u00f3n para la creaci\u00f3n por parte de Stephanie de las placas conmemorativas de bronce que ahora se entregan a <a href=\"http:\/\/www.mathunion.org\/imu-awards\/icm-emmy-noether-lecture\" target=\"_blank\" rel=\"noreferrer noopener\">los conferencistas Emmy Noether del ICM en la Conferencia Internacional de Matem\u00e1ticos que se celebra cada cuatro a\u00f1os.<\/a> Las dos f\u00f3rmulas se compusieron tambi\u00e9n para esa placa. (Puedes encontrar m\u00e1s informaci\u00f3n en<a href=\"https:\/\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/emmy-noether-more-info-mathemalchemy-art-installation.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> este art\u00edculo sobre esas placas<\/a>(PDF &#8211; 2,3 MB). <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"637\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/emmy-noether-25-mathemalchemy-art-installation.jpg?resize=900%2C637&#038;ssl=1\" alt=\"\" class=\"wp-image-4750\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/emmy-noether-25-mathemalchemy-art-installation.jpg?resize=1024%2C725&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/emmy-noether-25-mathemalchemy-art-installation.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/emmy-noether-25-mathemalchemy-art-installation.jpg?resize=768%2C544&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/emmy-noether-25-mathemalchemy-art-installation.jpg?resize=1200%2C849&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/emmy-noether-25-mathemalchemy-art-installation.jpg?w=1256&amp;ssl=1 1256w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Las f\u00f3rmulas se refieren a los dos resultados por los que Emmy Noether es m\u00e1s conocida: la formulaci\u00f3n de la<em> condici\u00f3n de la \u00abcadena ascendente de ideales principales\u00bb, <\/em>una propiedad fundamental de los anillos especiales, ahora llamados anillos noetherianos, y el <em>Teorema de Noether, <\/em>que afirma que toda invariancia de un sistema f\u00edsico bajo un grupo de transformaciones est\u00e1 ligada a una ley de conservaci\u00f3n, un resultado b\u00e1sico en f\u00edsica matem\u00e1tica. La p\u00e1gina impresa es el comienzo del art\u00edculo sobre ese segundo resultado. Sorprendentemente, estos dos resultados fundacionales son elementos b\u00e1sicos en dos subdisciplinas matem\u00e1ticas ahora tan alejadas que sus practicantes a menudo ni siquiera saben que Emmy Noether tambi\u00e9n es celebrada por los miembros de la otra disciplina.  <\/p>\n\n\n\n<p><\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Rhind papyrus<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/rhind-papyrus-26-mathemalchemy-art-installation.jpg?resize=685%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4763\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/rhind-papyrus-26-mathemalchemy-art-installation.jpg?resize=685%2C1024&amp;ssl=1 685w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/rhind-papyrus-26-mathemalchemy-art-installation.jpg?resize=201%2C300&amp;ssl=1 201w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/rhind-papyrus-26-mathemalchemy-art-installation.jpg?resize=768%2C1148&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/rhind-papyrus-26-mathemalchemy-art-installation.jpg?w=803&amp;ssl=1 803w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>El papiro Rhind data de (aproximadamente) 1650-1550 a.C.; es una de las fuentes matem\u00e1ticas egipcias m\u00e1s antiguas que se conocen. Contiene una lista de problemas de aritm\u00e9tica y \u00e1lgebra. Puede encontrar m\u00e1s informaci\u00f3n <a href=\"http:\/\/en.wikipedia.org\/wiki\/Rhind_Mathematical_Papyrus\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a>. Muchos otros artefactos antiguos que muestran la pr\u00e1ctica de las matem\u00e1ticas antes de los tiempos modernos, tanto en la antig\u00fcedad como posteriormente, y en muchas culturas diferentes, se pueden encontrar en l\u00ednea en <a href=\"https:\/\/www.history-of-mathematics.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">history-of-mathematics.org<\/a>   <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Eigenmodes of vibrating disk<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/eigenmodes-of-vibrating-disk-27-mathemalchemy-art-installation.jpg?resize=730%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4768\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/eigenmodes-of-vibrating-disk-27-mathemalchemy-art-installation.jpg?resize=730%2C1024&amp;ssl=1 730w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/eigenmodes-of-vibrating-disk-27-mathemalchemy-art-installation.jpg?resize=214%2C300&amp;ssl=1 214w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/eigenmodes-of-vibrating-disk-27-mathemalchemy-art-installation.jpg?resize=768%2C1078&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/eigenmodes-of-vibrating-disk-27-mathemalchemy-art-installation.jpg?w=855&amp;ssl=1 855w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Un disco vibrante sujeto por sus bordes tiene modos especiales de vibraci\u00f3n, similares a las vibraciones de tono puro de una cuerda vibrante.<\/p>\n\n\n\n<p>Son funciones propias del operador de Laplace Beltrami del disco. Las im\u00e1genes muestran dos ilustraciones de estas funciones propias; los valores propios m\u00e1s altos ( o los \u00abtonos\u00bb m\u00e1s altos de la vibraci\u00f3n) corresponden a una mayor oscilaci\u00f3n en la funci\u00f3n propia. Puede encontrar m\u00e1s informaci\u00f3n <a href=\"http:\/\/en.wikipedia.org\/wiki\/Vibrations_of_a_circular_membrane\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a>.  <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Vortices developing after cylindrical obstruction<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\" id=\"vortices\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/vortices-developing-after-cylindrical-obstruction-28-mathemalchemy-art-installation.jpg?resize=330%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4771\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/vortices-developing-after-cylindrical-obstruction-28-mathemalchemy-art-installation.jpg?resize=330%2C1024&amp;ssl=1 330w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/vortices-developing-after-cylindrical-obstruction-28-mathemalchemy-art-installation.jpg?resize=97%2C300&amp;ssl=1 97w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/vortices-developing-after-cylindrical-obstruction-28-mathemalchemy-art-installation.jpg?w=462&amp;ssl=1 462w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Cuando un flujo laminar (un flujo bonito y estable sin remolinos) se encuentra con un obst\u00e1culo cil\u00edndrico, desarrolla caracter\u00edsticas turbulentas consistentes en v\u00f3rtices que se \u00abdesprenden\u00bb del obst\u00e1culo, lo que se ha observado detalladamente en experimentos y se ha reproducido con gran exactitud en simulaciones num\u00e9ricas de las ecuaciones de Navier-Stokes calculadas digitalmente.<\/p>\n\n\n\n<p>Las vistas que aparecen en las hojas de la Cabalgata proceden de instant\u00e1neas de una simulaci\u00f3n num\u00e9rica realizada por<a href=\"http:\/\/amandaghassaei.com\/apps\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Amanda Ghassaei.<\/a> Estos v\u00f3rtices inspiraron el dise\u00f1o de los v\u00f3rtices en el flujo de aire que sale de la trompeta de la <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/siluetas-y-vortices-conexiones-matematicas\/#silhouettes\">ni\u00f1a Silueta<\/a> en Mathemalchemy.<\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n<\/div>\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Knots to Polyhedra<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1021\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knots-to-polyhedra-29-mathemalchemy-art-installation.jpg?resize=900%2C1021&#038;ssl=1\" alt=\"\" class=\"wp-image-4772\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knots-to-polyhedra-29-mathemalchemy-art-installation.jpg?resize=903%2C1024&amp;ssl=1 903w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knots-to-polyhedra-29-mathemalchemy-art-installation.jpg?resize=265%2C300&amp;ssl=1 265w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knots-to-polyhedra-29-mathemalchemy-art-installation.jpg?resize=768%2C870&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/knots-to-polyhedra-29-mathemalchemy-art-installation.jpg?w=1147&amp;ssl=1 1147w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Cada nudo tiene su correspondiente complemento de nudo, lo que significa que si se toma S<sup>3<\/sup>=R<sup>3<\/sup> U {\u221e} y se elimina el nudo (que es un c\u00edrculo encajado), el espacio resultante se denomina variedad tridimensional con c\u00faspide. La c\u00faspide est\u00e1 precisamente donde se ha eliminado el nudo. A cada complemento de nudo le corresponde una descomposici\u00f3n poli\u00e9drica, una forma de describir la geometr\u00eda de la variedad. El nudo de esta hoja ilustra el nudo de la Figura del Ocho y su correspondiente descomposici\u00f3n en dos tetraedros ideales (v\u00e9rtices eliminados). Las flechas y los colores ilustran c\u00f3mo deben pegarse los dos tetraedros para obtener el complemento de la Figura del Ocho.    <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>El nudo de Figura del Ocho tiene el menor volumen hiperb\u00f3lico. Esta descomposici\u00f3n fue demostrada por primera vez por William Thurston en sus notas <em>The Geometry and Topology of Three Manifolds.<\/em> <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Evolving wavelet<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<p>Las ond\u00edculas son bloques de construcci\u00f3n para <em>las transformadas wavelet o transformada de ond\u00edculas,<\/em>en las que funciones m\u00e1s generales se descomponen en una combinaci\u00f3n lineal de versiones escaladas y trasladadas de la plantilla, la ond\u00edcula. Estas transformadas son \u00fatiles en entornos en los que hay muchas escalas en juego. Por ejemplo, las transformadas de ond\u00edcula se utilizan en el tratamiento de im\u00e1genes y en la comprensi\u00f3n y descripci\u00f3n de singularidades en ecuaciones diferenciales u operadores integrales.   <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"686\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/evolving-wavelet-30-mathemalchemy-art-installation-1.jpg?resize=900%2C686&#038;ssl=1\" alt=\"\" class=\"wp-image-5072\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/evolving-wavelet-30-mathemalchemy-art-installation-1.jpg?resize=1024%2C781&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/evolving-wavelet-30-mathemalchemy-art-installation-1.jpg?resize=300%2C229&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/evolving-wavelet-30-mathemalchemy-art-installation-1.jpg?resize=768%2C586&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/evolving-wavelet-30-mathemalchemy-art-installation-1.jpg?resize=1200%2C916&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/evolving-wavelet-30-mathemalchemy-art-installation-1.jpg?w=1300&amp;ssl=1 1300w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Para algunas ond\u00edculas especialmente construidas, las versiones escaladas y trasladadas utilizadas en la transformada de ond\u00edculas constituyen una base ortonormal; est\u00e1n vinculadas a algoritmos de transformada con implementaciones num\u00e9ricas muy r\u00e1pidas que utilizan convoluciones con secuencias digitales cortas (tambi\u00e9n llamadas <em>filtros<\/em>). La superficie (de la que la hoja muestra dos vistas, por \u00abdelante\u00bb y por \u00abdetr\u00e1s\u00bb) ilustra una familia de 1 par\u00e1metro de esas ond\u00edculas especiales generadoras de bases correspondientes a filtros digitales con s\u00f3lo 4 coeficientes, que van desde la ond\u00edcula de Haar hasta la <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/mural-conexiones-matematicas\/\">\u00abond\u00edcula feroz\u00bb pintada por PulPi<\/a>; D4 est\u00e1 a unos 2\/3 del camino. <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Gerrymandering<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gerrymandering-31-mathemalchemy-art-installation.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4775\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gerrymandering-31-mathemalchemy-art-installation.jpg?resize=768%2C1025&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gerrymandering-31-mathemalchemy-art-installation.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gerrymandering-31-mathemalchemy-art-installation.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gerrymandering-31-mathemalchemy-art-installation.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gerrymandering-31-mathemalchemy-art-installation.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/gerrymandering-31-mathemalchemy-art-installation.jpg?w=850&amp;ssl=1 850w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>La elecci\u00f3n de representantes al Congreso en EEUU se organiza por estados; el n\u00famero de representantes a la C\u00e1mara de un estado es (aproximadamente) proporcional a su poblaci\u00f3n. Los estados con m\u00e1s de un representante en la C\u00e1mara se dividen en distritos congresionales que eligen un representante cada uno. Los l\u00edmites de estos distritos pueden volver a trazarse cada 10 a\u00f1os, para garantizar (aproximadamente) la misma poblaci\u00f3n por distrito. Los l\u00edmites de los distritos tambi\u00e9n pueden tener en cuenta otros factores; a veces se acusa a las autoridades que redibujan los l\u00edmites de <a href=\"http:\/\/en.wikipedia.org\/wiki\/Gerrymandering\" target=\"_blank\" rel=\"noreferrer noopener\">manipulaci\u00f3n\u00bbinjusta\u00bb<\/a>.    <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Los matem\u00e1ticos han desarrollado herramientas algor\u00edtmicas no partidistas para evaluar la \u00abequidad\u00bb de un mapa de distritos, por ejemplo comparando su resultado electoral con la distribuci\u00f3n de resultados de mapas geom\u00e9tricamente similares. Las im\u00e1genes de esta hoja proceden de varios estudios de este tipo, coordinados por <a href=\"http:\/\/mggg.org\/people\/mduchin\" target=\"_blank\" rel=\"noreferrer noopener\">Moon Duchin<\/a> y por <a href=\"http:\/\/sites.duke.edu\/quantifyinggerrymandering\/author\/0297691\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jonathan Mattingly<\/a>. <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Sea creatures\/Mollusk Shells<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<p>Los patrones se dan de forma natural en la naturaleza. Las conchas de moluscos como el Nautilus nacarado, el Syrinx aruanus y el Tectus niloticus (sin\u00f3nimo: Trochus niloticus) tienen una elegante estructura en espiral que sigue una \u00abespiral equiangular\u00bb, tambi\u00e9n conocida como \u00abespiral logar\u00edtmica\u00bb. Para cualquier \u00e1ngulo de rotaci\u00f3n, la distancia desde el origen de la espiral aumenta en una cantidad fija.  <\/p>\n\n\n\n<p>M\u00e1s informaci\u00f3n <a href=\"https:\/\/www.maa.org\/sites\/default\/files\/images\/upload_library\/23\/picado\/seashells\/espiraleng.html\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"477\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sea-creatures-mollusks-shells-32-mathemalchemy-art-installation.jpg?resize=900%2C477&#038;ssl=1\" alt=\"\" class=\"wp-image-4777\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sea-creatures-mollusks-shells-32-mathemalchemy-art-installation.jpg?resize=1024%2C543&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sea-creatures-mollusks-shells-32-mathemalchemy-art-installation.jpg?resize=300%2C159&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sea-creatures-mollusks-shells-32-mathemalchemy-art-installation.jpg?resize=768%2C407&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sea-creatures-mollusks-shells-32-mathemalchemy-art-installation.jpg?resize=1200%2C636&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sea-creatures-mollusks-shells-32-mathemalchemy-art-installation.jpg?w=1300&amp;ssl=1 1300w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Latex example<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"831\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/latex-exemple-33-mathemalchemy-art-installation.jpg?resize=831%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4779\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/latex-exemple-33-mathemalchemy-art-installation.jpg?resize=831%2C1024&amp;ssl=1 831w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/latex-exemple-33-mathemalchemy-art-installation.jpg?resize=244%2C300&amp;ssl=1 244w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/latex-exemple-33-mathemalchemy-art-installation.jpg?resize=768%2C946&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/latex-exemple-33-mathemalchemy-art-installation.jpg?w=974&amp;ssl=1 974w\" sizes=\"auto, (max-width: 831px) 100vw, 831px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Los matem\u00e1ticos consideran a LaTeX como una herramienta esencial, no para el c\u00e1lculo o la teor\u00eda matem\u00e1tica, sino para la comunicaci\u00f3n. En la actualidad, pr\u00e1cticamente todos los escritos matem\u00e1ticos se componen con LaTeX. En esta hoja, el c\u00f3digo LaTeX se muestra junto al resultado. El paquete tikz se utiliza para hacer la imagen, que muestra un rect\u00e1ngulo \u00e1ureo subdividido en cuadrados y rect\u00e1ngulos \u00e1ureos m\u00e1s peque\u00f1os. Esto ilustra la expansi\u00f3n de fracci\u00f3n continua de la proporci\u00f3n \u00e1urea, que se muestra con la figura.    <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Navajo geometry<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;69e7c65e58858&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"69e7c65e58858\" class=\"wp-block-image size-large has-lightbox wp-lightbox-container\" id=\"navajo\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/navajo-geometry-34-mathemalchemy-art-installation.jpg?resize=805%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4780\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/navajo-geometry-34-mathemalchemy-art-installation.jpg?resize=805%2C1024&amp;ssl=1 805w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/navajo-geometry-34-mathemalchemy-art-installation.jpg?resize=236%2C300&amp;ssl=1 236w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/navajo-geometry-34-mathemalchemy-art-installation.jpg?resize=768%2C977&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/navajo-geometry-34-mathemalchemy-art-installation.jpg?w=865&amp;ssl=1 865w\" sizes=\"auto, (max-width: 805px) 100vw, 805px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta hoja muestra varios ejemplos de la belleza geom\u00e9trica inherente a la cultura navajo, desde el tejido de cestas y alfombras hasta los dise\u00f1os octogonales, que pasan a cuadrados, en la construcci\u00f3n de las paredes y el tejado de un hogan tradicional.<\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">From knot to braid<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"784\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/from-knots-to-braid-35-mathemalchemy-art-installation.jpg?resize=784%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4782\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/from-knots-to-braid-35-mathemalchemy-art-installation.jpg?resize=784%2C1024&amp;ssl=1 784w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/from-knots-to-braid-35-mathemalchemy-art-installation.jpg?resize=230%2C300&amp;ssl=1 230w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/from-knots-to-braid-35-mathemalchemy-art-installation.jpg?resize=768%2C1003&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/from-knots-to-braid-35-mathemalchemy-art-installation.jpg?w=919&amp;ssl=1 919w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta hoja muestra la transformaci\u00f3n de un nudo concreto en una trenza; en la trenza resultante, los extremos correspondientes de las cuerdas pueden conectarse por pares, para cerrar la trenza. <a href=\"http:\/\/en.wikipedia.org\/wiki\/Alexander's_theorem\" target=\"_blank\" rel=\"noreferrer noopener\">El teorema de Alexander<\/a> afirma que todo nudo puede transformarse en una trenza cerrada de este tipo. La correspondencia no es \u00fanica: un nudo puede tener varias representaciones de trenza, pero existen algoritmos sistem\u00e1ticos para transformar una representaci\u00f3n en otra.<\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Thurston figures<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\" id=\"Thurston-figures\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"881\" height=\"1000\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/thurston-36-mathemalchemy-art-installation.jpg?resize=881%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-4783\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/thurston-36-mathemalchemy-art-installation.jpg?w=881&amp;ssl=1 881w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/thurston-36-mathemalchemy-art-installation.jpg?resize=264%2C300&amp;ssl=1 264w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/thurston-36-mathemalchemy-art-installation.jpg?resize=768%2C872&amp;ssl=1 768w\" sizes=\"auto, (max-width: 881px) 100vw, 881px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>William Thurston (1946-2012) fue un visionario geom\u00e9trico con un enfoque l\u00fadico, a veces incluso m\u00e1gico, de las matem\u00e1ticas. Una vez dijo   <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abLas matem\u00e1ticas son un proceso de mirar fijamente con suficiente perseverancia la niebla del embrollo y la confusi\u00f3n para acabar abri\u00e9ndose paso hacia una mayor claridad\u00bb. <\/p>\n<cite>William Thurston<\/cite><\/blockquote>\n\n\n\n<p>Ten\u00eda una imaginaci\u00f3n asombrosa y a menudo explicaba sus ideas mediante im\u00e1genes. \u00c9stas son figuras de su libro<em> Geometr\u00eda y Topolog\u00eda Tridimensionales, <\/em>Vol.1, 1997)<a href=\"http:\/\/www.ams.org\/notices\/201511\/rnoti-p1318.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">(vea m\u00e1s &#8211; enlace PDF<\/a>) <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n<\/div>\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Tricolorability<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"826\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tricolorability-37-mathemalchemy-art-installation.jpg?resize=826%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4784\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tricolorability-37-mathemalchemy-art-installation.jpg?resize=826%2C1024&amp;ssl=1 826w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tricolorability-37-mathemalchemy-art-installation.jpg?resize=242%2C300&amp;ssl=1 242w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tricolorability-37-mathemalchemy-art-installation.jpg?resize=768%2C952&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/tricolorability-37-mathemalchemy-art-installation.jpg?w=968&amp;ssl=1 968w\" sizes=\"auto, (max-width: 826px) 100vw, 826px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>La tricolorabilidad es quiz\u00e1 la <em>invariante<\/em> m\u00e1s sencilla de un nudo. Es decir, todo diagrama de un nudo dado es tricolorable si y s\u00f3lo si todos los dem\u00e1s diagramas son tricolorables. Esto nos permite, por ejemplo, saber con certeza que el tr\u00e9bol no es en realidad lo mismo que el nudo. La tricolorabilidad fue desarrollada por R. Fox hacia 1956 (v\u00e9ase <a href=\"https:\/\/arxiv.org\/abs\/math\/0608172\">https:\/\/arxiv.org\/abs\/math\/0608172,<\/a> p\u00e1gina 3).   <\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Katherine Johnson<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" id=\"Katherine-Johnson\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/katherine_johnson-38-mathemalchemy-art-project.jpg?resize=788%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-4786\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/katherine_johnson-38-mathemalchemy-art-project.jpg?resize=788%2C1024&amp;ssl=1 788w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/katherine_johnson-38-mathemalchemy-art-project.jpg?resize=231%2C300&amp;ssl=1 231w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/katherine_johnson-38-mathemalchemy-art-project.jpg?resize=768%2C997&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/katherine_johnson-38-mathemalchemy-art-project.jpg?w=847&amp;ssl=1 847w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Esta l\u00e1mina muestra la primera p\u00e1gina de uno de los informes t\u00e9cnicos de la NASA de Katherine Johnson, cuyos c\u00e1lculos manuales fueron esenciales para muchos de los primeros vuelos espaciales tripulados de la NASA en las d\u00e9cadas de 1950 y 1960. En los a\u00f1os que precedieron a este trabajo, ya era una pionera matem\u00e1tica, reclutada de su trabajo como maestra de escuela p\u00fablica para ser una de las tres primeras estudiantes graduadas negras de la Universidad de Virginia Occidental. Su contribuci\u00f3n m\u00e1s c\u00e9lebre al programa espacial estadounidense fueron sus c\u00e1lculos para el vuelo orbital de John Glenn en 1962. Debido a la complejidad de la ruta de vuelo, la NASA hab\u00eda creado una nueva red de ordenadores y estaciones de seguimiento para hacer posible la misi\u00f3n, pero las m\u00e1quinas eran propensas a los fallos y los astronautas eran reacios a confiar en ellas. Es famosa la negativa del propio Glenn a emprender la misi\u00f3n hasta que Johnson hubiera comprobado a mano cada uno de los resultados de los ordenadores.    <\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Katherine Johnson es una de las mujeres matem\u00e1ticas e ingenieras afroamericanas que aparecen en el libro de 2016 <em>Figuras ocultas<\/em> (escrito por Margot Lee Shetterly) y en su adaptaci\u00f3n cinematogr\u00e1fica, un homenaje largamente esperado a sus logros hist\u00f3ricos. El a\u00f1o anterior, a la edad de 97 a\u00f1os, Johnson recibi\u00f3 la Medalla Presidencial de la Libertad en reconocimiento a su trabajo pionero en la exploraci\u00f3n espacial. <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Triangles in different 2-dimensional geometries<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"455\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?resize=900%2C455&#038;ssl=1\" alt=\"\" class=\"wp-image-4787\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?resize=1024%2C518&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?resize=300%2C152&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?resize=768%2C389&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?resize=1536%2C777&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?resize=1200%2C607&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?resize=1568%2C793&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/sum-angles-triangle-38-mathemalchemy-art-installation.jpg?w=1690&amp;ssl=1 1690w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Desde peque\u00f1os nos han inculcado la noci\u00f3n de que la suma de los \u00e1ngulos de un tri\u00e1ngulo siempre es igual a 180 grados, es decir, \u03c0 radianes. Pero esto es s\u00f3lo una parte de la historia. Esta historia se remonta aproximadamente a 2300 a\u00f1os, cuando Euclides enunci\u00f3 los cinco axiomas de la geometr\u00eda. El quinto, conocido como el postulado de las paralelas, afirma   <\/p>\n\n\n\n<p><em>Si un <\/em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Line_segment\"><em>segmento de l\u00ednea<\/em><\/a><em> interseca dos rectas <\/em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Line_(mathematics)\"><em>rectas<\/em><\/a><em> formando dos \u00e1ngulos interiores del mismo lado que sumen menos de dos <\/em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Right_angle\"><em>\u00e1ngulos rectos<\/em><\/a><em>entonces las dos rectas, si se prolongan indefinidamente, se encuentran en aquel lado en el que los \u00e1ngulos suman menos de dos \u00e1ngulos rectos.<\/em><\/p>\n\n\n\n<p>M\u00e1s popularmente, el postulado de la paralela equivale a la siguiente afirmaci\u00f3n:<a href=\"https:\/\/www.britannica.com\/science\/line-mathematics\"> <em>por un punto que no est\u00e1 en una recta dada<\/em> <em><em>hay exactamente una recta paralela a la recta dada<\/em><\/em>.<\/a> Se puede demostrar que esta afirmaci\u00f3n implica que la suma de los \u00e1ngulos de un tri\u00e1ngulo debe ser igual a \u03c0 radianes.<\/p>\n\n\n\n<p>Durante dos milenios, los matem\u00e1ticos intentaron demostrar el quinto postulado a partir de los cuatro anteriores, sin \u00e9xito. En el siglo XIX, matem\u00e1ticos como Lobachevski y Bolyai descubrieron una nueva geometr\u00eda seleccionando un quinto axioma alternativo, en el que se supone que a trav\u00e9s de un punto que no est\u00e1 en una l\u00ednea dada hay al menos dos l\u00edneas paralelas a la l\u00ednea dada. Esto da lugar a una geometr\u00eda en la que la suma de los \u00e1ngulos de un tri\u00e1ngulo debe ser inferior a \u03c0 radianes.  <\/p>\n\n\n\n<p>Tambi\u00e9n se pueden considerar otras alternativas al quinto axioma de Euclides, y construir as\u00ed una geometr\u00eda no euclidiana. M\u00e1s concretamente, se podr\u00eda suponer que a trav\u00e9s de un punto que no est\u00e9 en una recta dada <em>no <\/em>hay rectas paralelas a la recta dada. Un ejemplo de este tipo de geometr\u00eda es la geometr\u00eda esf\u00e9rica, en la que los grandes c\u00edrculos asumen el papel de las rectas. En los tri\u00e1ngulos de una esfera, la suma de los tres \u00e1ngulos es siempre superior a \u03c0 radianes.   <\/p>\n\n\n\n<p>Tres l\u00e1minas hermanas muestran figuras triangulares para las tres geometr\u00edas. En el caso hiperb\u00f3lico, la suma de los \u00e1ngulos es inferior a \u03c0 radianes; en el caso el\u00edptico, la suma supera \u03c0 radianes. En ambos casos, el valor de la diferencia es igual al \u00e1rea del tri\u00e1ngulo. En el caso eucl\u00eddeo, que separa el el\u00edptico del hiperb\u00f3lico y puede considerarse como el l\u00edmite a medida que el radio de la esfera (pseudoesfera) se aproxima al infinito, la suma de los tres \u00e1ngulos es exactamente igual a \u03c0 radianes para <em>todos los<\/em> tri\u00e1ngulos, y no da ninguna informaci\u00f3n sobre su \u00e1rea.   <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Transformations of Conway\u2019s knot<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"878\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/transformation-of-conway-s-knot-40-mathemalchemy-art-installation.jpg?resize=900%2C878&#038;ssl=1\" alt=\"\" class=\"wp-image-4862\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/transformation-of-conway-s-knot-40-mathemalchemy-art-installation.jpg?resize=1024%2C999&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/transformation-of-conway-s-knot-40-mathemalchemy-art-installation.jpg?resize=300%2C293&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/transformation-of-conway-s-knot-40-mathemalchemy-art-installation.jpg?resize=768%2C749&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/transformation-of-conway-s-knot-40-mathemalchemy-art-installation.jpg?resize=1200%2C1170&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/transformation-of-conway-s-knot-40-mathemalchemy-art-installation.jpg?w=1288&amp;ssl=1 1288w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Este diagrama fue tomado del art\u00edculo <a href=\"https:\/\/arxiv.org\/abs\/1808.02923\" target=\"_blank\" rel=\"noreferrer noopener\"><em>The Conway Knot is not slice<\/em> d<\/a>e Lisa Piccirillo, en el cual ella demostr\u00f3 una conjetura que llevaba mucho tiempo abierta sobre el nudo de Conway, no mucho antes de que empezara el proyecto de MatemAlquimia<\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Native Code Talkers<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"783\" height=\"652\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/Screenshot-2025-12-04-190626.png?resize=783%2C652&#038;ssl=1\" alt=\"\" class=\"wp-image-14865\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/Screenshot-2025-12-04-190626.png?w=783&amp;ssl=1 783w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/Screenshot-2025-12-04-190626.png?resize=300%2C250&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/Screenshot-2025-12-04-190626.png?resize=768%2C640&amp;ssl=1 768w\" sizes=\"auto, (max-width: 783px) 100vw, 783px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Los codigoparlantes amerindios sirvieron en primera l\u00ednea en ambas guerras mundiales, manteniendo las comunicaciones t\u00e1cticas estadounidenses invulnerables a los fisgones enemigos, lo que salv\u00f3 miles de vidas estadounidenses y aliadas.<br\/>Los entonces eficaces codificadores para las comunicaciones de voz no eran adecuados para el uso t\u00e1ctico; los codigoparlantes proporcionaban una seguridad absoluta y una velocidad de cifrado y descifrado esenciales en el campo de batalla.<br\/>Los primeros codigoparlantes fueron choctaws en la Primera Guerra Mundial. En la II Guerra Mundial, los codigoparlantes de muchas tribus sirvieron en los teatros de operaciones de \u00c1frica del Norte,<br\/>Europa y el Pac\u00edfico; los codigoparlantes navajo (o din\u00e9) se han convertido en los<br\/>m\u00e1s famosos. Los primeros 29 reclutas codigoparlantes Navajos de la Infanter\u00eda de Marina de EE.UU. completaron su formaci\u00f3n en 1942.<br\/>Adem\u00e1s de la formaci\u00f3n b\u00e1sica, estos hombres tuvieron que desarrollar y memorizar un c\u00f3digo militar \u00fanico utilizando su propio idioma. El primer tipo de c\u00f3digo que crearon consist\u00eda en 26 t\u00e9rminos navajos que representaban las<br\/>letras inglesas individuales utilizadas para deletrear una palabra. Por ejemplo, la palabra navajo para hormiga, wo-la-chee, se utiliz\u00f3 para<br\/>representar la letra \u00aba\u00bb en ingl\u00e9s. Adem\u00e1s, elaboraron un diccionario de 211 t\u00e9rminos (ampliado posteriormente a<br\/>411) para palabras y nombres militares ingleses que no exist\u00edan originalmente en la lengua navajo. Por ejemplo,<br\/>como no exist\u00eda una palabra navajo para submarino, los codificadores acordaron utilizar el t\u00e9rmino besh-lo,<br\/>que se traduce como pez de hierro.<br\/>Los codificadores fueron esenciales para la comunicaci\u00f3n t\u00e1ctica en muchas batallas importantes, como en la playa de Utah<br\/>durante la invasi\u00f3n del D\u00eda D en Francia, y en Iwo Jima en el Pac\u00edfico. El oficial de se\u00f1ales de la 5\u00aa Divisi\u00f3n de Marines<br\/>declar\u00f3: \u00abSi no fuera por los navajos, los marines nunca habr\u00edan tomado Iwo Jima\u00bb. Durante la batalla,<br\/>seis codificadores navajos trabajaron sin descanso, enviando y recibiendo m\u00e1s de 800 mensajes sin errores, una haza\u00f1a<br\/>fundamental para ganar la batalla.<br\/>Sus c\u00f3digos nunca se descifraron, y su trabajo permaneci\u00f3 en secreto durante d\u00e9cadas tras el final de la Segunda Guerra Mundial. En 2001<br\/>se concedieron Medallas de Oro del Congreso a los Navajo y a otros habladores de c\u00f3digos. M\u00e1s informaci\u00f3n se puede encontrar          <br\/><a href=\"http:\/\/www.nationalww2museum.org\/war\/articles\/american-indian-code-talkers\">aqu\u00ed:<\/a><\/p>\n<\/div>\n<\/div>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Arnold\u2019s cat<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"608\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/arnold-s-cat-c1-mathemalchemy-art-installation.jpg?resize=900%2C608&#038;ssl=1\" alt=\"\" class=\"wp-image-4813\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/arnold-s-cat-c1-mathemalchemy-art-installation.jpg?resize=1024%2C692&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/arnold-s-cat-c1-mathemalchemy-art-installation.jpg?resize=300%2C203&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/arnold-s-cat-c1-mathemalchemy-art-installation.jpg?resize=768%2C519&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/arnold-s-cat-c1-mathemalchemy-art-installation.jpg?resize=1200%2C811&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/arnold-s-cat-c1-mathemalchemy-art-installation.jpg?w=1453&amp;ssl=1 1453w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>El famoso matem\u00e1tico Vladimir Arnold ilustr\u00f3 las propiedades de mezcla de un mapa simple del cuadrado [0,1<sup>]2<\/sup> a s\u00ed mismo dibujando un gato en el cuadrado, y mostrando c\u00f3mo el dibujo en blanco y negro era transformado por el mapa. Este dibujo y esta construcci\u00f3n han llegado a conocerse como \u00ab<a href=\"http:\/\/en.wikipedia.org\/wiki\/Arnold's_cat_map\" target=\"_blank\" rel=\"noreferrer noopener\">el gato de Arnold<\/a>\u00ab; inspiraron el nombre del <a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/05\/panaderia-conexiones-matematicas\/\">panadero de la Matemalquimia<\/a>. El mapa, tal como se ilustra aqu\u00ed, consta de varios pasos: en primer lugar, la transformaci\u00f3n lineal de <strong>R<\/strong> <sup>2<\/sup> con la matriz [1 1;1 2], que transforma [0,1<sup>]2<\/sup> en un paralelogramo; a continuaci\u00f3n, las piezas que sobresalen de [0,1<sup>]2<\/sup> se vuelven a colocar en [0,1<sup>]2<\/sup> a\u00f1adiendo los m\u00faltiplos enteros apropiados de los vectores [1;0] y [0;1]; las secciones que requieren un vector de transporte distinto reciben un color diferente. Los cuatro tri\u00e1ngulos resultantes embaldosan bien [0,1<sup>]2<\/sup>. Como resultado de la operaci\u00f3n, el gato se ha comprimido en una direcci\u00f3n y se ha \u00abemborronado\u00bb en otra. Repitiendo el mapa una y otra vez, ver\u00e1s que la imagen transformada del gato se aproxima a un gris uniforme constante.     <\/p>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"\/>\n<\/div>\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Baker\u2019s map on Cat<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<figure class=\"wp-block-image size-large\" id=\"baker-s-map-on-cat\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"455\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/baker-s-map-on-cat-c2-mathemalchemy-art-installation.jpg?resize=900%2C455&#038;ssl=1\" alt=\"Mapeo del Panadero sobre un gato.\" class=\"wp-image-4815\" title=\"\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/baker-s-map-on-cat-c2-mathemalchemy-art-installation.jpg?resize=1024%2C518&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/baker-s-map-on-cat-c2-mathemalchemy-art-installation.jpg?resize=300%2C152&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/baker-s-map-on-cat-c2-mathemalchemy-art-installation.jpg?resize=768%2C389&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/baker-s-map-on-cat-c2-mathemalchemy-art-installation.jpg?resize=1200%2C607&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/baker-s-map-on-cat-c2-mathemalchemy-art-installation.jpg?w=1446&amp;ssl=1 1446w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>El <a href=\"http:\/\/en.wikipedia.org\/wiki\/Baker's_map\" target=\"_blank\" rel=\"noreferrer noopener\">mapeo del Panadero <\/a> es otro mapa de [0,1<sup>]2<\/sup> a s\u00ed mismo que es fuertemente<a href=\"http:\/\/en.wikipedia.org\/wiki\/Mixing_(mathematics)\" target=\"_blank\" rel=\"noreferrer noopener\"> mezclante.<\/a> En el mapeo del Panadero tradicional (seg\u00fan los matem\u00e1ticos), primero se \u00abaplana\u00bb el cuadrado (aplicando la transformaci\u00f3n lineal con matriz [2 0;0 \u00bd]) y luego se \u00abcorta\u00bb el trozo que sobresale en el cuadrado vecino y se vuelve a colocar \u00abencima\u00bb traslad\u00e1ndolo mediante el vector [-1;\u00bd]. Sin embargo, los verdaderos panaderos suelen doblar la masa extendida, por eso mostramos una versi\u00f3n culinariamente m\u00e1s fiel, con un gato \u00abdoblado\u00bb; este mapeo tambi\u00e9n es fuertemente mezclante.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-primary-color has-text-color has-background wp-element-button\" href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/terraza-conexiones-matematicas\/#baker-map\" style=\"background-color:#f4a811\"> Mire c\u00f3mo el mapeo del Panadero tambi\u00e9n est\u00e1 presente en la Terraza <\/a><\/div>\n<\/div>\n<\/div><\/details><\/div>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading has-text-align-left has-primary-color has-text-color has-huge-font-size\" id=\"read-more-about-the-ball-arches-1\">M\u00e1s informaci\u00f3n sobre la Cabalgata<\/h3>\n<div class=\"wp-block-newspack-blocks-carousel slides-per-view-2 wpnbpc\" id=\"wp-block-newspack-carousel__1\" data-current-post-id=13831 data-slides-per-view=2 data-slide-count=3 data-aspect-ratio=0.75><div class=\"swiper\"><div class=\"swiper-wrapper\">\n\t\t\t<article data-post-id=\"13773\" class=\"post-has-image swiper-slide tag-cabalgata category-fabricacion-de-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/04\/23\/cavalcade-fabricacion\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?fit=900%2C900&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Cavalcade &#8211; Fabricaci\u00f3n\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?resize=200%2C200&amp;ssl=1 200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13774\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/04\/23\/cavalcade-fabricacion\/installation-cavalcade-nas-dominique-ehrmann-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?fit=1200%2C1200&amp;ssl=1\" data-orig-size=\"1200,1200\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Dominique installing Cavalcade at NAS&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/installation-cavalcade-NAS-dominique-ehrmann-mathemalchemy-art-installation.jpg?fit=900%2C900&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/04\/23\/cavalcade-fabricacion\/\" rel=\"bookmark\">Cavalcade &#8211; Fabricaci\u00f3n<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13807\" class=\"post-has-image swiper-slide tag-arquimedes tag-cabalgata tag-convergente tag-copos-de-nieve-de-koch tag-criba-de-eratostanes tag-diagrama-de-venn tag-el-gato-de-arnold tag-emmy-noether-es tag-eureka-es tag-extension-del-lema-de-dehn tag-flujo-laminar tag-galois-es tag-geometria tag-gerrymandering-es tag-grupos-de-papel-tapiz tag-henry-segerman-es tag-katherine-johnson-es tag-mapeo-del-panadero tag-martin-gardner-es tag-mezclado-aditivo tag-minkowski-es tag-molusco tag-navajo-es tag-nudo-de-conway tag-nudos tag-papiro-rhind tag-pitagoras tag-plano-de-fano tag-plano-hiperbolico tag-primos tag-tetraedro-de-sierpinski tag-triangulaciones-ideales-tensas tag-tricolorabilidad tag-vortice tag-vladimir-arnold-es tag-wavelet-ondicula tag-william-thurston-es tag-yves-bouligand-es category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=768%2C1024&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Cabalgata &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?resize=900%2C1200&amp;ssl=1 900w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?resize=600%2C800&amp;ssl=1 600w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?resize=150%2C200&amp;ssl=1 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" data-attachment-id=\"13808\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/silhouette-adult-teen-in-context-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&amp;ssl=1\" data-orig-size=\"1000,1333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"silhouette-adult-teen-in-context-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=768%2C1024&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/\" rel=\"bookmark\">Cabalgata &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13831\" class=\"post-has-image swiper-slide tag-cabalgata category-non-classe type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/cabalgata-a-traves-del-espejo-de-matemalquimia\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"649\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mathematician-cat-cavalcade-mathemalchemy-art-installation.jpg?fit=900%2C649&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Cabalgata &#8211; A trav\u00e9s del espejo de MatemAlquimia\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mathematician-cat-cavalcade-mathemalchemy-art-installation.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mathematician-cat-cavalcade-mathemalchemy-art-installation.jpg?resize=300%2C216&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mathematician-cat-cavalcade-mathemalchemy-art-installation.jpg?resize=1024%2C738&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mathematician-cat-cavalcade-mathemalchemy-art-installation.jpg?resize=768%2C554&amp;ssl=1 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13832\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/cabalgata-a-traves-del-espejo-de-matemalquimia\/mathematician-cat-cavalcade-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mathematician-cat-cavalcade-mathemalchemy-art-installation.jpg?fit=1200%2C865&amp;ssl=1\" data-orig-size=\"1200,865\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mathematician-cat-cavalcade-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/mathematician-cat-cavalcade-mathemalchemy-art-installation.jpg?fit=900%2C649&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/cabalgata-a-traves-del-espejo-de-matemalquimia\/\" rel=\"bookmark\">Cabalgata &#8211; A trav\u00e9s del espejo de MatemAlquimia<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t<\/div><button class=\"swiper-button swiper-button-prev\" aria-label=\"Diapositiva anterior\" ><\/button><button class=\"swiper-button swiper-button-next\" aria-label=\"Diapositiva siguiente\" ><\/button><\/div><div class=\"swiper-pagination-bullets\" ><button option=\"0\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 1\" selected><\/button><button option=\"1\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 2\" ><\/button><button option=\"2\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 3\" ><\/button><\/div><\/div>\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-right has-large-font-size\" id=\"next-mathematical-connections-in-knotical\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/bahia-de-nudos-conexiones-matematicas\/\">Siguiente: Conexiones matem\u00e1ticas en la Bah\u00eda de Nudos<\/a><\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-style-default coblocks-animate\" data-coblocks-animation=\"slideInRight\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/03\/knotical-boat-mathemalchemy-art-installation-rev_mars2022.png?resize=800%2C800&#038;ssl=1\" alt=\"Bah&#xED;a de nudos\" class=\"wp-image-6635\" title=\"icono-matemalquimia\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/03\/knotical-boat-mathemalchemy-art-installation-rev_mars2022.png?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/03\/knotical-boat-mathemalchemy-art-installation-rev_mars2022.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/03\/knotical-boat-mathemalchemy-art-installation-rev_mars2022.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/03\/knotical-boat-mathemalchemy-art-installation-rev_mars2022.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/03\/knotical-boat-mathemalchemy-art-installation-rev_mars2022.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/03\/knotical-boat-mathemalchemy-art-installation-rev_mars2022.png?resize=200%2C200&amp;ssl=1 200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"125\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/back-to-mathemalchemy.jpg?resize=627%2C125&#038;ssl=1\" alt=\"Escenas de MatemAlquimia\" class=\"wp-image-6648\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/back-to-mathemalchemy.jpg?w=627&amp;ssl=1 627w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/back-to-mathemalchemy.jpg?resize=300%2C60&amp;ssl=1 300w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-black-background-color has-background\" href=\"https:\/\/mathemalchemy.org\/es\/conexiones-matematicas\/\">Ir a conexiones matem\u00e1ticas<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-cover alignfull\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" class=\"wp-block-cover__image-background wp-image-5030\" alt=\"\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=900%2C900&#038;ssl=1\" style=\"object-position:62% 91%\" data-object-fit=\"cover\" data-object-position=\"62% 91%\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?resize=1568%2C1568&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/cavalcade-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-primary-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-background-color has-text-color has-large-font-size\" id=\"explore-mathematical-connections-in-other-scenes\">Explore las Conexiones Matem\u00e1ticas en otras escenas<\/h3>\n\n\n<div class=\"wp-block-newspack-blocks-carousel wp-block-newspack-blocks-carousel__autoplay-playing slides-per-view-1 wpnbpc\" id=\"wp-block-newspack-carousel__2\" data-current-post-id=13851 data-slides-per-view=1 data-slide-count=13 data-aspect-ratio=0.75 data-autoplay=1 data-autoplay_delay=5><button aria-label=\"Pausar la presentaci\u00f3n\" class=\"swiper-button swiper-button-pause\"><\/button><button aria-label=\"Reproducir la presentaci\u00f3n\" class=\"swiper-button swiper-button-play\"><\/button><div class=\"swiper\"><div class=\"swiper-wrapper\">\n\t\t\t<article data-post-id=\"14494\" class=\"post-has-image swiper-slide tag-grupos-de-papel-tapiz tag-mesas-de-frisos category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2024\/05\/14\/tablas-de-friso-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"324\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?fit=900%2C324&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Mesas de frisos &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?w=1300&amp;ssl=1 1300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?resize=300%2C108&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?resize=1024%2C369&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?resize=768%2C277&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?resize=1200%2C433&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"14496\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2024\/05\/14\/tablas-de-friso-conexiones-matematicas\/frieze_tables_mouse-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?fit=1300%2C469&amp;ssl=1\" data-orig-size=\"1300,469\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Frieze_Tables_mouse\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2024\/05\/Frieze_Tables_mouse.png?fit=900%2C324&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2024\/05\/14\/tablas-de-friso-conexiones-matematicas\/\" rel=\"bookmark\">Mesas de frisos &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13761\" class=\"post-has-image swiper-slide tag-blockchain-es tag-codigo-de-hamming tag-codigo-morse tag-cifrado-cesar tag-colcha tag-enigma-es tag-escitala tag-escudo tag-huella-dactilar tag-quilt-de-criptografia tag-quipu-es tag-tejido category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2023\/11\/07\/quiltito-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?fit=900%2C900&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Quiltito &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?w=1256&amp;ssl=1 1256w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?resize=200%2C200&amp;ssl=1 200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13766\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2023\/11\/07\/quiltito-conexiones-matematicas\/cryptography-quilt-boston-mathemalchemy-math-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?fit=1256%2C1256&amp;ssl=1\" data-orig-size=\"1256,1256\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"cryptography-quilt-boston-mathemalchemy-math-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2023\/01\/cryptography-quilt-boston-mathemalchemy-math-art-installation.jpg?fit=900%2C900&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2023\/11\/07\/quiltito-conexiones-matematicas\/\" rel=\"bookmark\">Quiltito &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13794\" class=\"post-has-image swiper-slide category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/23\/colcha-de-criptografia-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"881\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?fit=900%2C881&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Colcha de criptograf\u00eda &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?w=1256&amp;ssl=1 1256w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?resize=300%2C294&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?resize=1024%2C1002&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?resize=768%2C751&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?resize=1200%2C1174&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13795\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/23\/colcha-de-criptografia-conexiones-matematicas\/central-padlock-cryptography-quilt-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?fit=1256%2C1229&amp;ssl=1\" data-orig-size=\"1256,1229\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"central-padlock-cryptography-quilt-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/central-padlock-cryptography-quilt-mathemalchemy-art-installation.jpg?fit=900%2C881&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/23\/colcha-de-criptografia-conexiones-matematicas\/\" rel=\"bookmark\">Colcha de criptograf\u00eda &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13632\" class=\"post-has-image swiper-slide tag-siluetas tag-vortice tag-vortices category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/siluetas-y-vortices-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"793\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?fit=900%2C793&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Siluetas y v\u00f3rtices &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?w=1900&amp;ssl=1 1900w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?resize=300%2C264&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?resize=1024%2C902&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?resize=768%2C677&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?resize=1536%2C1353&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?resize=1200%2C1057&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?resize=1568%2C1381&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13633\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/siluetas-y-vortices-conexiones-matematicas\/silhouette-child-in-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?fit=1900%2C1674&amp;ssl=1\" data-orig-size=\"1900,1674\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"silhouette-child-in-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-child-in-mathemalchemy-art-installation.jpg?fit=900%2C793&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/12\/siluetas-y-vortices-conexiones-matematicas\/\" rel=\"bookmark\">Siluetas y v\u00f3rtices &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"14448\" class=\"post-has-image swiper-slide tag-anillos-de-borromeo tag-abaco tag-botella-de-klein tag-celdas-de-voronoi tag-curva-de-harris tag-edmund-harriss-es tag-fibracion-de-hopf tag-grupos-de-papel-tapiz tag-john-conway-es tag-la-esfera-cornuda-de-alexander tag-moebius-es tag-nudo-de-conway tag-origami-es tag-solidos-arquimedianos tag-tienda-de-curiosidades tag-variedad category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/tienda-de-curiosidades-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?fit=900%2C900&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Tienda de curiosidades &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?w=1900&amp;ssl=1 1900w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?resize=1568%2C1568&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"14449\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/tienda-de-curiosidades-conexiones-matematicas\/curio-shop-conway-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?fit=1900%2C1900&amp;ssl=1\" data-orig-size=\"1900,1900\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"curio-shop-conway-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/curio-shop-conway-mathemalchemy-art-installation.jpg?fit=900%2C900&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/tienda-de-curiosidades-conexiones-matematicas\/\" rel=\"bookmark\">Tienda de curiosidades &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13621\" class=\"post-has-image swiper-slide tag-wavelet-ondicula category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/mural-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"485\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/finished-mural-with-mahl-stick-mathemalchemy.jpg?fit=900%2C485&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Mural &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/finished-mural-with-mahl-stick-mathemalchemy.jpg?w=1113&amp;ssl=1 1113w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/finished-mural-with-mahl-stick-mathemalchemy.jpg?resize=300%2C162&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/finished-mural-with-mahl-stick-mathemalchemy.jpg?resize=1024%2C552&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/finished-mural-with-mahl-stick-mathemalchemy.jpg?resize=768%2C414&amp;ssl=1 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13619\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/24\/mural-a-traves-del-espejo-de-matemalquimia\/mathemalchemy-2-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/finished-mural-with-mahl-stick-mathemalchemy.jpg?fit=1113%2C600&amp;ssl=1\" data-orig-size=\"1113,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Mathemalchemy Group&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;https:\/\/mathemalchemy.org\/&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Mathemalchemy&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Mathemalchemy\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;The mural in detail&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/finished-mural-with-mahl-stick-mathemalchemy.jpg?fit=900%2C485&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/mural-conexiones-matematicas\/\" rel=\"bookmark\">Mural &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13837\" class=\"post-has-image swiper-slide tag-adoquinado category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/gran-pagina-de-garabatos-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"399\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?fit=900%2C399&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Gran p\u00e1gina de garabatos &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?resize=300%2C133&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?resize=1024%2C454&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?resize=768%2C341&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?resize=1536%2C681&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?resize=1200%2C532&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?resize=1568%2C695&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13838\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/gran-pagina-de-garabatos-conexiones-matematicas\/great-doodle-page-mathemalchemy-art-installation-5\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?fit=2000%2C887&amp;ssl=1\" data-orig-size=\"2000,887\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"great-doodle-page-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Edge of the Great Doodle Page&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/great-doodle-page-mathemalchemy-art-installation.jpg?fit=900%2C399&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/gran-pagina-de-garabatos-conexiones-matematicas\/\" rel=\"bookmark\">Gran p\u00e1gina de garabatos &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13682\" class=\"post-has-image swiper-slide tag-adoquinado tag-arrecife tag-criba-de-eratostanes tag-enteros-gaussianos tag-geometria tag-geometria-no-euclidiana tag-hexagono tag-jardin-es tag-la-esfera-cornuda-de-alexander tag-origami-es tag-primos tag-solidos-de-johnson category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/jardin-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"510\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/chipmunks-sorting-primes-mathemalchemy-art-installation.jpg?fit=700%2C510&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Jard\u00edn &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/chipmunks-sorting-primes-mathemalchemy-art-installation.jpg?w=700&amp;ssl=1 700w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/chipmunks-sorting-primes-mathemalchemy-art-installation.jpg?resize=300%2C219&amp;ssl=1 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" data-attachment-id=\"13683\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/jardin-conexiones-matematicas\/chipmunks-sorting-primes-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/chipmunks-sorting-primes-mathemalchemy-art-installation.jpg?fit=700%2C510&amp;ssl=1\" data-orig-size=\"700,510\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"chipmunks-sorting-primes-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/chipmunks-sorting-primes-mathemalchemy-art-installation.jpg?fit=700%2C510&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/jardin-conexiones-matematicas\/\" rel=\"bookmark\">Jard\u00edn &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13641\" class=\"post-has-image swiper-slide category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/pila-de-libros-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?fit=900%2C675&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Pila de libros &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?resize=800%2C600&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?resize=200%2C150&amp;ssl=1 200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13642\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/pila-de-libros-conexiones-matematicas\/assembling-3-stack-of-books-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?fit=1200%2C900&amp;ssl=1\" data-orig-size=\"1200,900\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"assembling-3-Stack-of-books-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Dominique Ehrmann and Ingrid Daubechies assembling the Stack of Books&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/04\/assembling-3-Stack-of-books-mathemalchemy-art-installation.jpg?fit=900%2C675&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/pila-de-libros-conexiones-matematicas\/\" rel=\"bookmark\">Pila de libros &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"14453\" class=\"post-has-image swiper-slide tag-dodecahedro tag-faro tag-gps-es tag-heptagono tag-lentes-de-fresnel tag-proyeccion-estereografica tag-trayectoria-dodecaedrica category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/faro-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"475\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?fit=900%2C475&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Faro &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?w=2258&amp;ssl=1 2258w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?resize=300%2C158&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?resize=1024%2C541&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?resize=768%2C405&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?resize=1536%2C811&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?resize=2048%2C1081&amp;ssl=1 2048w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?resize=1200%2C633&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?resize=1568%2C828&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"14454\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/faro-conexiones-matematicas\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?fit=2258%2C1192&amp;ssl=1\" data-orig-size=\"2258,1192\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/lighthouse-fresnel-stereographic-projection-mathemalchemy-art-installation.jpg?fit=900%2C475&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/faro-conexiones-matematicas\/\" rel=\"bookmark\">Faro &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13656\" class=\"post-has-image swiper-slide tag-adoquinado tag-copos-de-nieve-de-koch tag-disco-de-poincare tag-fractal tag-fractales tag-heptagono tag-hotel-hilbert tag-integracion-de-lebesgue tag-integracion-de-riemann tag-la-paradoja-de-zenon tag-papalote-tetraedrico tag-plano-hiperbolico tag-tetraedro-de-sierpinski tag-tortuga category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/tortuga-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?fit=800%2C800&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Tortuga &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?resize=200%2C200&amp;ssl=1 200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" data-attachment-id=\"13657\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/tortuga-conexiones-matematicas\/mathemalchemy-8-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?fit=800%2C800&amp;ssl=1\" data-orig-size=\"800,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Mathemalchemy Group&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;https:\/\/mathemalchemy.org\/&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Mathemalchemy&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Mathemalchemy\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;https:\/\/mathemalchemy.org\/&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2021\/08\/tortoise-story-mathematical-concepts-mathemalchemy-2.jpg?fit=800%2C800&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/tortuga-conexiones-matematicas\/\" rel=\"bookmark\">Tortuga &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13842\" class=\"post-has-image swiper-slide tag-convergente tag-primos category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/arcos-de-pelotas-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?fit=900%2C675&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Arcos de Pelotas &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?w=1900&amp;ssl=1 1900w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=800%2C600&amp;ssl=1 800w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=200%2C150&amp;ssl=1 200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?resize=1568%2C1176&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13843\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/arcos-de-pelotas-conexiones-matematicas\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?fit=1900%2C1425&amp;ssl=1\" data-orig-size=\"1900,1425\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ball-arches-temari-converging-diverging-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/ball-arches-temari-converging-diverging-mathemalchemy-art-installation.jpg?fit=900%2C675&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/11\/arcos-de-pelotas-conexiones-matematicas\/\" rel=\"bookmark\">Arcos de Pelotas &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t\n\t\t\t<article data-post-id=\"13851\" class=\"post-has-image swiper-slide tag-adoquinado tag-arnold tag-orbita-periodica tag-billares-pentagonales tag-circulos tag-conjunto-de-apolonio tag-disco-hiperbolico tag-ecuacion-de-schroedinger tag-el-gato-de-arnold tag-el-gato-de-schroedinger tag-fractal tag-geodesicas tag-geometria tag-grupos-de-papel-tapiz tag-heptagono tag-inversion-del-circulo tag-mandelbrot tag-marjorie-rice tag-moser tag-panaderia tag-pentagono tag-perlas-de-indra tag-sistema-dinamico tag-teselacion tag-topologia tag-tsp tag-variedad tag-vias-del-tren category-conceptos-matematicos-en-matemalquimia category-conexiones-matematicas-en-matemalquimia type-post post\">\n\t\t\t\t\t\t\t\t<figure class=\"post-thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/05\/panaderia-conexiones-matematicas\/\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"599\" src=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?fit=900%2C599&amp;ssl=1\" class=\"image-fit-cover wp-post-image\" alt=\"Panader\u00eda &#8211; Conexiones matem\u00e1ticas\" object-fit=\"cover\" layout=\"fill\" srcset=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?resize=1568%2C1045&amp;ssl=1 1568w, https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" data-attachment-id=\"13849\" data-permalink=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/06\/panaderia-a-traves-del-espejo-de-matemalquimia\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?fit=2000%2C1333&amp;ssl=1\" data-orig-size=\"2000,1333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;This work is licensed under a Creative Commons Attribution-NonCommercial-NoDerivatives 4.0 International License&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/bakery-mathematical-concepts-mathematics-mathemalchemy-art-installation.jpg?fit=900%2C599&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t\t\t\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/05\/panaderia-conexiones-matematicas\/\" rel=\"bookmark\">Panader\u00eda &#8211; Conexiones matem\u00e1ticas<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t\t\t\t\t\t\t<\/article>\n\t\t\t<\/div><button class=\"swiper-button swiper-button-prev\" aria-label=\"Diapositiva anterior\" ><\/button><button class=\"swiper-button swiper-button-next\" aria-label=\"Diapositiva siguiente\" ><\/button><\/div><div class=\"swiper-pagination-bullets\" ><button option=\"0\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 1\" selected><\/button><button option=\"1\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 2\" ><\/button><button option=\"2\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 3\" ><\/button><button option=\"3\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 4\" ><\/button><button option=\"4\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 5\" ><\/button><button option=\"5\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 6\" ><\/button><button option=\"6\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 7\" ><\/button><button option=\"7\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 8\" ><\/button><button option=\"8\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 9\" ><\/button><button option=\"9\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 10\" ><\/button><button option=\"10\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 11\" ><\/button><button option=\"11\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 12\" ><\/button><button option=\"12\" class=\"swiper-pagination-bullet\" aria-label=\"Ir a la diapositiva 13\" ><\/button><\/div><\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"taxonomy-post_tag has-text-align-left pas-de-meta wp-block-post-terms has-small-font-size\"><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/arquimedes\/\" rel=\"tag\">Arqu\u00edmedes<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/cabalgata\/\" rel=\"tag\">Cabalgata<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/convergente\/\" rel=\"tag\">convergente<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/copos-de-nieve-de-koch\/\" rel=\"tag\">Copos de nieve de Koch<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/criba-de-eratostanes\/\" rel=\"tag\">Criba de Erat\u00f3stanes<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/diagrama-de-venn\/\" rel=\"tag\">Diagrama de Venn<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/el-gato-de-arnold\/\" rel=\"tag\">El gato de Arnold<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/emmy-noether-es\/\" rel=\"tag\">Emmy Noether<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/eureka-es\/\" rel=\"tag\">Eureka<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/extension-del-lema-de-dehn\/\" rel=\"tag\">Extensi\u00f3n del lema de Dehn<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/flujo-laminar\/\" rel=\"tag\">flujo laminar<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/galois-es\/\" rel=\"tag\">Galois<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/geometria\/\" rel=\"tag\">geometr\u00eda<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/gerrymandering-es\/\" rel=\"tag\">gerrymandering<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/grupos-de-papel-tapiz\/\" rel=\"tag\">grupos de papel tapiz<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/henry-segerman-es\/\" rel=\"tag\">Henry Segerman<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/katherine-johnson-es\/\" rel=\"tag\">Katherine Johnson<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/mapeo-del-panadero\/\" rel=\"tag\">Mapeo del panadero<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/martin-gardner-es\/\" rel=\"tag\">Martin Gardner<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/mezclado-aditivo\/\" rel=\"tag\">Mezclado aditivo<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/minkowski-es\/\" rel=\"tag\">Minkowski<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/molusco\/\" rel=\"tag\">molusco<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/navajo-es\/\" rel=\"tag\">navajo<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/nudo-de-conway\/\" rel=\"tag\">Nudo de Conway<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/nudos\/\" rel=\"tag\">nudos<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/papiro-rhind\/\" rel=\"tag\">Papiro Rhind<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/pitagoras\/\" rel=\"tag\">Pit\u00e1goras<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/plano-de-fano\/\" rel=\"tag\">Plano de Fano<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/plano-hiperbolico\/\" rel=\"tag\">plano hiperb\u00f3lico<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/primos\/\" rel=\"tag\">primos<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/tetraedro-de-sierpinski\/\" rel=\"tag\">Tetraedro de Sierpi\u0144ski<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/triangulaciones-ideales-tensas\/\" rel=\"tag\">triangulaciones ideales tensas<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/tricolorabilidad\/\" rel=\"tag\">tricolorabilidad<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/vortice\/\" rel=\"tag\">V\u00f3rtice<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/vladimir-arnold-es\/\" rel=\"tag\">Vladimir Arnold<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/wavelet-ondicula\/\" rel=\"tag\">wavelet (ond\u00edcula)<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/william-thurston-es\/\" rel=\"tag\">William Thurston<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/mathemalchemy.org\/es\/tag\/yves-bouligand-es\/\" rel=\"tag\">Yves Bouligand<\/a><\/div>\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sobre la Cabalgata La colecci\u00f3n de hojas es muy diversa, y abarca desde figuras interesantes y\/o bellas a divertidas an\u00e9cdotas, pasando por visualizaciones \u00abaj\u00e1\u00bb y documentos o reflexiones hist\u00f3ricas; algunas de ellas rinden homenaje a un matem\u00e1tico concreto. No hay ninguna raz\u00f3n matem\u00e1tica que justifique su orden aqu\u00ed: se trata simplemente del orden en que<a class=\"more-link\" href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/\">Sigue leyendo <span class=\"screen-reader-text\">\u00abCabalgata &#8211; Conexiones matem\u00e1ticas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":44503792,"featured_media":13808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7393,7394],"tags":[7427,7426,7417,7414,7399,7434,7420,7440,7430,7435,7442,7431,7401,7443,7419,7428,7448,7425,7437,7433,7438,7444,7445,7423,7418,7441,7436,7432,7421,7398,7415,7429,7447,7424,7416,7422,7446,7439],"class_list":["post-13807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conceptos-matematicos-en-matemalquimia","category-conexiones-matematicas-en-matemalquimia","tag-arquimedes","tag-cabalgata","tag-convergente","tag-copos-de-nieve-de-koch","tag-criba-de-eratostanes","tag-diagrama-de-venn","tag-el-gato-de-arnold","tag-emmy-noether-es","tag-eureka-es","tag-extension-del-lema-de-dehn","tag-flujo-laminar","tag-galois-es","tag-geometria","tag-gerrymandering-es","tag-grupos-de-papel-tapiz","tag-henry-segerman-es","tag-katherine-johnson-es","tag-mapeo-del-panadero","tag-martin-gardner-es","tag-mezclado-aditivo","tag-minkowski-es","tag-molusco","tag-navajo-es","tag-nudo-de-conway","tag-nudos","tag-papiro-rhind","tag-pitagoras","tag-plano-de-fano","tag-plano-hiperbolico","tag-primos","tag-tetraedro-de-sierpinski","tag-triangulaciones-ideales-tensas","tag-tricolorabilidad","tag-vortice","tag-vladimir-arnold-es","tag-wavelet-ondicula","tag-william-thurston-es","tag-yves-bouligand-es","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cabalgata - Conexiones matem\u00e1ticas - Mathemalchemy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cabalgata - Conexiones matem\u00e1ticas - Mathemalchemy\" \/>\n<meta property=\"og:description\" content=\"Sobre la Cabalgata La colecci\u00f3n de hojas es muy diversa, y abarca desde figuras interesantes y\/o bellas a divertidas an\u00e9cdotas, pasando por visualizaciones \u00abaj\u00e1\u00bb y documentos o reflexiones hist\u00f3ricas; algunas de ellas rinden homenaje a un matem\u00e1tico concreto. No hay ninguna raz\u00f3n matem\u00e1tica que justifique su orden aqu\u00ed: se trata simplemente del orden en queSigue leyendo &quot;Cabalgata &#8211; Conexiones matem\u00e1ticas&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Mathemalchemy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mathemalchemy-103377841519027\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-19T21:33:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T19:54:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mathemalchemy team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mathemalchemy team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"33 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/\"},\"author\":{\"name\":\"mathemalchemy team\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#\\\/schema\\\/person\\\/bcd1d0a50ff45c4951f837be7a1ac1e2\"},\"headline\":\"Cabalgata &#8211; Conexiones matem\u00e1ticas\",\"datePublished\":\"2022-01-19T21:33:35+00:00\",\"dateModified\":\"2025-12-15T19:54:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/\"},\"wordCount\":6675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/mathemalchemy.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1\",\"keywords\":[\"Arqu\u00edmedes\",\"Cabalgata\",\"convergente\",\"Copos de nieve de Koch\",\"Criba de Erat\u00f3stanes\",\"Diagrama de Venn\",\"El gato de Arnold\",\"Emmy Noether\",\"Eureka\",\"Extensi\u00f3n del lema de Dehn\",\"flujo laminar\",\"Galois\",\"geometr\u00eda\",\"gerrymandering\",\"grupos de papel tapiz\",\"Henry Segerman\",\"Katherine Johnson\",\"Mapeo del panadero\",\"Martin Gardner\",\"Mezclado aditivo\",\"Minkowski\",\"molusco\",\"navajo\",\"Nudo de Conway\",\"nudos\",\"Papiro Rhind\",\"Pit\u00e1goras\",\"Plano de Fano\",\"plano hiperb\u00f3lico\",\"primos\",\"Tetraedro de Sierpi\u0144ski\",\"triangulaciones ideales tensas\",\"tricolorabilidad\",\"V\u00f3rtice\",\"Vladimir Arnold\",\"wavelet (ond\u00edcula)\",\"William Thurston\",\"Yves Bouligand\"],\"articleSection\":[\"Conceptos matem\u00e1ticos en MatemAlquimia\",\"Conexiones matem\u00e1ticas en MatemAlquimia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/\",\"url\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/\",\"name\":\"Cabalgata - Conexiones matem\u00e1ticas - Mathemalchemy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/mathemalchemy.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1\",\"datePublished\":\"2022-01-19T21:33:35+00:00\",\"dateModified\":\"2025-12-15T19:54:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mathemalchemy.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mathemalchemy.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1\",\"width\":1000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/2022\\\/01\\\/19\\\/cabalgata-conexiones-matematicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cabalgata &#8211; Conexiones matem\u00e1ticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#website\",\"url\":\"https:\\\/\\\/mathemalchemy.org\\\/\",\"name\":\"Mathemalchemy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mathemalchemy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#organization\",\"name\":\"Mathemalchemy\",\"url\":\"https:\\\/\\\/mathemalchemy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mathemalchemy.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-mathemalchemy.png?fit=270%2C243&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mathemalchemy.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-mathemalchemy.png?fit=270%2C243&ssl=1\",\"width\":270,\"height\":243,\"caption\":\"Mathemalchemy\"},\"image\":{\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mathemalchemy-103377841519027\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCykfzVmgUTr_8sFd42-BQNw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mathemalchemy.org\\\/#\\\/schema\\\/person\\\/bcd1d0a50ff45c4951f837be7a1ac1e2\",\"name\":\"mathemalchemy team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06ca2394c774c62d638f4957236e28f07afd87f038b73d04f5edcfe9f19d7a30?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06ca2394c774c62d638f4957236e28f07afd87f038b73d04f5edcfe9f19d7a30?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06ca2394c774c62d638f4957236e28f07afd87f038b73d04f5edcfe9f19d7a30?s=96&d=identicon&r=g\",\"caption\":\"mathemalchemy team\"},\"url\":\"https:\\\/\\\/mathemalchemy.org\\\/es\\\/author\\\/mathemalchemy-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cabalgata - Conexiones matem\u00e1ticas - Mathemalchemy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/","og_locale":"es_ES","og_type":"article","og_title":"Cabalgata - Conexiones matem\u00e1ticas - Mathemalchemy","og_description":"Sobre la Cabalgata La colecci\u00f3n de hojas es muy diversa, y abarca desde figuras interesantes y\/o bellas a divertidas an\u00e9cdotas, pasando por visualizaciones \u00abaj\u00e1\u00bb y documentos o reflexiones hist\u00f3ricas; algunas de ellas rinden homenaje a un matem\u00e1tico concreto. No hay ninguna raz\u00f3n matem\u00e1tica que justifique su orden aqu\u00ed: se trata simplemente del orden en queSigue leyendo \"Cabalgata &#8211; Conexiones matem\u00e1ticas\"","og_url":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/","og_site_name":"Mathemalchemy","article_publisher":"https:\/\/www.facebook.com\/Mathemalchemy-103377841519027","article_published_time":"2022-01-19T21:33:35+00:00","article_modified_time":"2025-12-15T19:54:01+00:00","og_image":[{"width":1000,"height":1333,"url":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1","type":"image\/jpeg"}],"author":"mathemalchemy team","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mathemalchemy team","Tiempo de lectura":"33 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#article","isPartOf":{"@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/"},"author":{"name":"mathemalchemy team","@id":"https:\/\/mathemalchemy.org\/#\/schema\/person\/bcd1d0a50ff45c4951f837be7a1ac1e2"},"headline":"Cabalgata &#8211; Conexiones matem\u00e1ticas","datePublished":"2022-01-19T21:33:35+00:00","dateModified":"2025-12-15T19:54:01+00:00","mainEntityOfPage":{"@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/"},"wordCount":6675,"commentCount":0,"publisher":{"@id":"https:\/\/mathemalchemy.org\/#organization"},"image":{"@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1","keywords":["Arqu\u00edmedes","Cabalgata","convergente","Copos de nieve de Koch","Criba de Erat\u00f3stanes","Diagrama de Venn","El gato de Arnold","Emmy Noether","Eureka","Extensi\u00f3n del lema de Dehn","flujo laminar","Galois","geometr\u00eda","gerrymandering","grupos de papel tapiz","Henry Segerman","Katherine Johnson","Mapeo del panadero","Martin Gardner","Mezclado aditivo","Minkowski","molusco","navajo","Nudo de Conway","nudos","Papiro Rhind","Pit\u00e1goras","Plano de Fano","plano hiperb\u00f3lico","primos","Tetraedro de Sierpi\u0144ski","triangulaciones ideales tensas","tricolorabilidad","V\u00f3rtice","Vladimir Arnold","wavelet (ond\u00edcula)","William Thurston","Yves Bouligand"],"articleSection":["Conceptos matem\u00e1ticos en MatemAlquimia","Conexiones matem\u00e1ticas en MatemAlquimia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/","url":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/","name":"Cabalgata - Conexiones matem\u00e1ticas - Mathemalchemy","isPartOf":{"@id":"https:\/\/mathemalchemy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#primaryimage"},"image":{"@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1","datePublished":"2022-01-19T21:33:35+00:00","dateModified":"2025-12-15T19:54:01+00:00","breadcrumb":{"@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#primaryimage","url":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1","width":1000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/mathemalchemy.org\/es\/2022\/01\/19\/cabalgata-conexiones-matematicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mathemalchemy.org\/es\/"},{"@type":"ListItem","position":2,"name":"Cabalgata &#8211; Conexiones matem\u00e1ticas"}]},{"@type":"WebSite","@id":"https:\/\/mathemalchemy.org\/#website","url":"https:\/\/mathemalchemy.org\/","name":"Mathemalchemy","description":"","publisher":{"@id":"https:\/\/mathemalchemy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mathemalchemy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mathemalchemy.org\/#organization","name":"Mathemalchemy","url":"https:\/\/mathemalchemy.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mathemalchemy.org\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2020\/09\/logo-mathemalchemy.png?fit=270%2C243&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2020\/09\/logo-mathemalchemy.png?fit=270%2C243&ssl=1","width":270,"height":243,"caption":"Mathemalchemy"},"image":{"@id":"https:\/\/mathemalchemy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mathemalchemy-103377841519027","https:\/\/www.youtube.com\/channel\/UCykfzVmgUTr_8sFd42-BQNw"]},{"@type":"Person","@id":"https:\/\/mathemalchemy.org\/#\/schema\/person\/bcd1d0a50ff45c4951f837be7a1ac1e2","name":"mathemalchemy team","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06ca2394c774c62d638f4957236e28f07afd87f038b73d04f5edcfe9f19d7a30?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06ca2394c774c62d638f4957236e28f07afd87f038b73d04f5edcfe9f19d7a30?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06ca2394c774c62d638f4957236e28f07afd87f038b73d04f5edcfe9f19d7a30?s=96&d=identicon&r=g","caption":"mathemalchemy team"},"url":"https:\/\/mathemalchemy.org\/es\/author\/mathemalchemy-team\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mathemalchemy.org\/wp-content\/uploads\/2022\/01\/silhouette-adult-teen-in-context-mathemalchemy-art-installation.jpg?fit=1000%2C1333&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pcmH52-3AH","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/posts\/13807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/users\/44503792"}],"replies":[{"embeddable":true,"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/comments?post=13807"}],"version-history":[{"count":23,"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/posts\/13807\/revisions"}],"predecessor-version":[{"id":14928,"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/posts\/13807\/revisions\/14928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/media\/13808"}],"wp:attachment":[{"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/media?parent=13807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/categories?post=13807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mathemalchemy.org\/es\/wp-json\/wp\/v2\/tags?post=13807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}